{"id":5939,"date":"2024-11-20T09:00:00","date_gmt":"2024-11-20T03:30:00","guid":{"rendered":"https:\/\/www.srotefeatures.in\/srote\/?p=5939"},"modified":"2024-11-14T14:50:14","modified_gmt":"2024-11-14T09:20:14","slug":"%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be","status":"publish","type":"post","link":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/","title":{"rendered":"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940"},"content":{"rendered":"\n<p><strong>\u0938\u0902\u0915\u0932\u0928<\/strong><strong>: <\/strong><strong>\u0915\u0947<\/strong><strong>. <\/strong><strong>\u0936\u0936\u093f\u0915\u0932\u093e<\/strong><strong><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"282\" height=\"352\" src=\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg\" alt=\"\" class=\"wp-image-5940\" style=\"width:674px;height:auto\" srcset=\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg 282w, https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee-240x300.jpg 240w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/><\/figure>\n\n\n\n<p><em>\u092e\u0939\u093f\u0932\u093e<\/em><em> <\/em><em>\u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902<\/em><em> <\/em><em>\u0915\u0940<\/em><em> <\/em><em>\u092c\u093e\u0924<\/em><em> <\/em><em>\u0915\u0930\u0947\u0902<\/em><em> <\/em><em>\u0924\u094b<\/em><em> <\/em><em>\u0907\u0915\u094d\u0915\u093e<\/em><em>&#8211;<\/em><em>\u0926\u0941\u0915\u094d\u0915\u093e<\/em><em> <\/em><em>\u0928\u093e\u092e<\/em><em> <\/em><em>\u0939\u0940<\/em><em> <\/em><em>\u0938\u093e\u092e\u0928\u0947<\/em><em> <\/em><em>\u0906\u0924\u0947<\/em><em> <\/em><em>\u0939\u0948\u0902\u0964<\/em><em> <\/em><em>\u090f\u0915<\/em><em> <\/em><em>\u0915\u093e\u0930\u0923<\/em><em> <\/em><em>\u0939\u0948<\/em><em> <\/em><em>\u0915\u093f<\/em><em> <\/em><em>\u0938\u093e\u092e\u093e\u091c\u093f\u0915<\/em><em> <\/em><em>\u0905\u0938\u092e\u093e\u0928\u0924\u093e\u0913\u0902<\/em><em> <\/em><em>\u0914\u0930<\/em><em> <\/em><em>\u0930\u0942\u0922\u093c\u093f\u0935\u093e\u0926\u0940<\/em><em> <\/em><em>\u092e\u093e\u0928\u094d\u092f\u0924\u093e\u0913\u0902<\/em><em> <\/em><em>\u0915\u0947<\/em><em> <\/em><em>\u091a\u0932\u0924\u0947<\/em><em> <\/em><em>\u092c\u0939\u0941\u0924<\/em><em> <\/em><em>\u0915\u092e<\/em><em> <\/em><em>\u092e\u0939\u093f\u0932\u093e\u090f\u0902<\/em><em> <\/em><em>\u0909\u091a\u094d\u091a<\/em><em> <\/em><em>\u0936\u093f\u0915\u094d\u0937\u093e<\/em><em> <\/em><em>\u0939\u093e\u0938\u093f\u0932<\/em><em> <\/em><em>\u0915\u0930<\/em><em> <\/em><em>\u092a\u093e\u0924\u0940<\/em><em> <\/em><em>\u0939\u0948\u0902<\/em><em>, <\/em><em>\u0935\u0939<\/em><em> <\/em><em>\u092d\u0940<\/em><em> <\/em><em>\u0905\u0915\u094d\u0938\u0930<\/em><em> <\/em><em>\u0924\u092e\u093e\u092e<\/em><em> <\/em><em>\u0938\u0902\u0918\u0930\u094d\u0937\u094b\u0902<\/em><em> <\/em><em>\u0938\u0947<\/em><em> <\/em><em>\u0917\u0941\u091c\u093c\u0930\u0924\u0947<\/em><em> <\/em><em>\u0939\u0941\u090f\u0964<\/em><em><\/em><\/p>\n\n\n\n<p><em>\u0926\u0942\u0938\u0930\u093e<\/em><em> <\/em><em>\u0915\u093e\u0930\u0923<\/em><em> <\/em><em>\u092f\u0939<\/em><em> <\/em><em>\u0939\u0948<\/em><em> <\/em><em>\u0915\u093f<\/em><em> <\/em><em>\u091c\u094b<\/em><em> <\/em><em>\u092e\u0939\u093f\u0932\u093e\u090f\u0902<\/em><em> <\/em><em>\u0935\u093f\u091c\u094d\u091e\u093e\u0928<\/em><em> <\/em><em>\u092e\u0947\u0902<\/em><em> <\/em><em>\u0936\u094b\u0927\u0930\u0924<\/em><em> <\/em><em>\u0939\u0948\u0902<\/em><em>, <\/em><em>\u0909\u0928\u0915\u0947<\/em><em> <\/em><em>\u092c\u093e\u0930\u0947<\/em><em> <\/em><em>\u092e\u0947\u0902<\/em><em> <\/em><em>\u0932\u094b\u0917\u094b\u0902<\/em><em> <\/em><em>\u0915\u094b<\/em><em> <\/em><em>\u092c\u0939\u0941\u0924<\/em><em> <\/em><em>\u0939\u0940<\/em><em> <\/em><em>\u0915\u092e<\/em><em> <\/em><em>\u092a\u0922\u093c\u0928\u0947<\/em><em> <\/em><em>\u0915\u094b<\/em><em> <\/em><em>\u092e\u093f\u0932\u0924\u093e<\/em><em> <\/em><em>\u0939\u0948\u0964<\/em><em> <\/em><em>\u0907\u0938<\/em><em> <\/em><em>\u0915\u092e\u0940<\/em><em> <\/em><em>\u0915\u094b<\/em><em> <\/em><em>\u092a\u093e\u091f\u0928\u0947<\/em><em> <\/em><em>\u0915\u093e<\/em><em> <\/em><em>\u090f\u0915<\/em><em> <\/em><em>\u092a\u094d\u0930\u092f\u093e\u0938<\/em><em> <\/em><em>\u0915\u093f\u092f\u093e<\/em><em> <\/em><em>\u0925\u093e<\/em><em> <\/em><em>\u0930\u094b\u0939\u093f\u0923\u0940<\/em><em> <\/em><em>\u0917\u094b\u0921\u092c\u094b\u0932\u0947<\/em><em> <\/em><em>\u0914\u0930<\/em><em> <\/em><em>\u0930\u093e\u092e<\/em><em> <\/em><em>\u0930\u093e\u092e\u0938\u094d\u0935\u093e\u092e\u0940<\/em><em> <\/em><em>\u0928\u0947<\/em><em> <\/em><em>\u0932\u0940\u0932\u093e\u0935\u0924\u0940\u091c\u093c<\/em><em> <\/em><em>\u0921\u0949\u091f\u0930\u094d\u0938<\/em><em> <\/em><em>\u0928\u093e\u092e\u0915<\/em><em> <\/em><em>\u092a\u0941\u0938\u094d\u0924\u0915<\/em><em> <\/em><em>\u092e\u0947\u0902\u0964<\/em><em> <\/em><em>\u0907\u0938\u092e\u0947\u0902<\/em><em> <\/em><em>\u092d\u093e\u0930\u0924<\/em><em> <\/em><em>\u0915\u0940<\/em><em> <\/em><em>\u0938\u094c<\/em><em> <\/em><em>\u092e\u0939\u093f\u0932\u093e<\/em><em> <\/em><em>\u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902<\/em><em> <\/em><em>\u0915\u0947<\/em><em> <\/em><em>\u0915\u093e\u092e<\/em><em>, <\/em><em>\u0935\u093f\u091a\u093e\u0930<\/em><em> <\/em><em>\u0935<\/em><em> <\/em><em>\u0938\u0902\u0918\u0930\u094d\u0937\u094b\u0902<\/em><em> <\/em><em>\u0915\u0940<\/em><em> <\/em><em>\u0917\u093e\u0925\u093e<\/em><em> <\/em><em>\u0939\u0948\u0964<\/em><em><\/em><\/p>\n\n\n\n<p><em>\u0905\u0917\u0932\u0947 \u0915\u0941\u091b \u0905\u0902\u0915\u094b\u0902 \u092e\u0947\u0902 \u0939\u092e \u0907\u0938 \u092a\u0941\u0938\u094d\u0924\u0915 \u0915\u0940 \u0915\u0941\u091b \u091c\u0940\u0935\u0928\u093f\u092f\u093e\u0902 \u0906\u092a \u0924\u0915 \u092a\u0939\u0941\u0902\u091a\u093e\u090f\u0902\u0917\u0947\u0964<\/em><\/p>\n\n\n\n<p>\u092e\u0947\u0930\u093e \u091c\u0928\u094d\u092e \u091c\u0928\u0935\u0930\u0940 1922 \u092e\u0947\u0902 \u090f\u0915 \u092a\u094d\u0930\u0917\u0924\u093f\u0936\u0940\u0932 \u0914\u0930 \u0916\u0941\u0932\u0947 \u0935\u093f\u091a\u093e\u0930\u094b\u0902 \u0935\u093e\u0932\u0947 \u092a\u0930\u093f\u0935\u093e\u0930 \u092e\u0947\u0902 \u0939\u0941\u0906 \u0925\u093e\u0964 \u092e\u0948\u0902 \u092d\u0932\u0947 \u0939\u0940 \u092e\u0941\u0902\u0939 \u092e\u0947\u0902 \u091a\u093e\u0902\u0926\u0940 \u0915\u093e \u091a\u092e\u094d\u092e\u091a \u0932\u0947\u0915\u0930 \u092a\u0948\u0926\u093e \u0928 \u0939\u0941\u0908 \u0939\u094b, \u0932\u0947\u0915\u093f\u0928 \u0939\u093e\u0925\u094b\u0902 \u092e\u0947\u0902 \u0915\u093f\u0924\u093e\u092c\u0947\u0902 \u0932\u0947\u0915\u0930 \u091c\u093c\u0930\u0942\u0930 \u092a\u0948\u0926\u093e \u0939\u0941\u0908 \u0925\u0940! \u092e\u0947\u0930\u093e \u092a\u0930\u093f\u0935\u093e\u0930 \u0915\u093e\u092b\u0940 \u092c\u0921\u093c\u093e (\u0938\u0902\u092f\u0941\u0915\u094d\u0924) \u092a\u0930\u093f\u0935\u093e\u0930 \u0925\u093e, \u091c\u094b \u0909\u0928 \u0926\u093f\u0928\u094b\u0902 \u0915\u093e\u092b\u0940 \u0906\u092e \u092c\u093e\u0924 \u0925\u0940\u0964 \u092a\u0930\u093f\u0935\u093e\u0930 \u0915\u0947 \u0938\u092d\u0940 \u0932\u094b\u0917 \u0915\u093e\u092b\u0940 \u092a\u0922\u093c\u0947-\u0932\u093f\u0916\u0947 \u0925\u0947\u0964 \u092f\u0939\u093e\u0902 \u0924\u0915 \u0915\u093f \u0932\u0921\u093c\u0915\u093f\u092f\u093e\u0902 \u092d\u0940, \u0914\u0930 \u0939\u092e\u0947\u0902 \u0939\u0930 \u0909\u0938 \u0917\u0924\u093f\u0935\u093f\u0927\u093f \u092e\u0947\u0902 \u092d\u093e\u0917 \u0932\u0947\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092a\u094d\u0930\u094b\u0924\u094d\u0938\u093e\u0939\u093f\u0924 \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0925\u093e \u091c\u094b \u0939\u092e\u0947\u0902 \u092a\u0938\u0902\u0926 \u0925\u0940 \u092f\u093e \u091c\u093f\u0938\u092e\u0947\u0902 \u0939\u092e \u092d\u093e\u0917 \u0932\u0947\u0928\u093e \u091a\u093e\u0939\u0924\u0947 \u0925\u0947\u0964 \u092e\u0947\u0930\u0940 \u0926\u093e\u0926\u0940, \u0915\u092e\u0932\u092e\u094d\u092e\u093e \u0926\u093e\u0938\u092a\u094d\u092a\u093e, \u0924\u0924\u094d\u0915\u093e\u0932\u0940\u0928 \u092e\u0948\u0938\u0942\u0930 \u0930\u093e\u091c\u094d\u092f \u0915\u0940 \u0938\u0930\u094d\u0935\u092a\u094d\u0930\u0925\u092e \u092e\u0939\u093f\u0932\u093e \u0938\u094d\u0928\u093e\u0924\u0915\u094b\u0902 \u092e\u0947\u0902 \u0938\u0947 \u090f\u0915 \u0925\u0940\u0902\u0964 \u0935\u0947 \u092e\u0939\u093f\u0932\u093e\u0913\u0902 \u0915\u0940 \u0936\u093f\u0915\u094d\u0937\u093e (women&#8217;s education), \u0916\u093e\u0938\u0915\u0930 \u0935\u093f\u0927\u0935\u093e \u0914\u0930 \u092a\u0930\u093f\u0924\u094d\u092f\u0915\u094d\u0924 \u092e\u0939\u093f\u0932\u093e\u0913\u0902 \u0915\u0940 \u0936\u093f\u0915\u094d\u0937\u093e, \u0915\u0947 \u0932\u093f\u090f \u092c\u0939\u0941\u0924 \u0938\u0915\u094d\u0930\u093f\u092f \u0925\u0940\u0902\u0964 \u0932\u0921\u093c\u0915\u093f\u092f\u094b\u0902 \u0915\u0940 \u0936\u093f\u0915\u094d\u0937\u093e (girls&#8217; education) \u092e\u0947\u0902 \u092e\u0926\u0926 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0909\u0928\u094d\u0939\u094b\u0902\u0928\u0947 \u090f\u0915 \u0924\u094d\u0935\u0930\u093f\u0924 \u0938\u094d\u0915\u0942\u0932 \u092a\u093e\u0920\u094d\u092f\u0915\u094d\u0930\u092e \u0938\u094d\u0925\u093e\u092a\u093f\u0924 \u0915\u0930\u0928\u0947 \u0915\u0940 \u092a\u0939\u0932 \u0915\u0940 \u0925\u0940, \u091c\u093f\u0938\u0915\u0947 \u0924\u0939\u0924 \u091b\u093e\u0924\u094d\u0930\u093e\u0913\u0902 \u0915\u094b 14 \u0935\u0930\u094d\u0937 \u0915\u0940 \u0906\u092f\u0941 \u0924\u0915 \u0905\u092a\u0928\u093e \u092e\u0948\u091f\u094d\u0930\u093f\u0915\u0941\u0932\u0947\u0936\u0928 \u092a\u0942\u0930\u0940 \u0915\u0930\u0928\u0947 \u0915\u0940 \u0907\u091c\u093e\u091c\u093c\u0924 \u0925\u0940\u0964 \u092f\u0939 \u092a\u093e\u0920\u094d\u092f\u0915\u094d\u0930\u092e \u2018\u092e\u0939\u093f\u0932\u093e \u0938\u0947\u0935\u093e \u0938\u092e\u093e\u091c\u2019 \u0926\u094d\u0935\u093e\u0930\u093e \u0938\u0902\u091a\u093e\u0932\u093f\u0924 \u2018\u0935\u093f\u0936\u0947\u0937 \u0905\u0902\u0917\u094d\u0930\u0947\u091c\u093c\u0940 \u0938\u094d\u0915\u0942\u0932 (Special English School)\u2019 \u092e\u0947\u0902 \u091a\u0932\u093e\u092f\u093e \u0917\u092f\u093e \u0925\u093e\u0964<\/p>\n\n\n\n<p>\u0907\u0938 \u0915\u094b\u0930\u094d\u0938 \u0915\u0947 \u0924\u0939\u0924 \u092e\u0948\u0902\u0928\u0947 \u0914\u0930 \u092e\u0947\u0930\u0947 \u0915\u0941\u091b \u091a\u091a\u0947\u0930\u0940-\u092e\u092e\u0947\u0930\u0940 \u092c\u0939\u0928\u094b\u0902 \u0928\u0947 \u092a\u0922\u093c\u093e\u0908 \u0915\u0940\u0964 \u091a\u0942\u0902\u0915\u093f \u092e\u0941\u091d\u0947 \u0905\u0924\u0940\u0924 \u0915\u0940 \u0918\u091f\u0928\u093e\u0913\u0902 \u0915\u0947 \u092c\u093e\u0930\u0947 \u092e\u0947\u0902 \u092a\u0922\u093c\u0928\u093e \u0914\u0930 \u0938\u0940\u0916\u0928\u093e \u0905\u091a\u094d\u091b\u093e \u0932\u0917\u0924\u093e \u0925\u093e, \u091c\u094b \u0915\u093f \u0906\u091c \u092d\u0940 \u0939\u0948, \u0907\u0938\u0932\u093f\u090f \u0938\u094d\u0915\u0942\u0932 \u0915\u0940 \u092a\u0922\u093c\u093e\u0908 \u092a\u0942\u0930\u0940 \u0939\u094b\u0928\u0947 \u0915\u0947 \u092c\u093e\u0926 \u0906\u0917\u0947 \u0915\u0940 \u092a\u0922\u093c\u093e\u0908 \u0915\u0947 \u0932\u093f\u090f \u092e\u0948\u0902\u0928\u0947 \u0907\u0924\u093f\u0939\u093e\u0938 (history) \u0935\u093f\u0937\u092f \u0915\u0930\u0940\u092c-\u0915\u0930\u0940\u092c \u091a\u0941\u0928 \u0939\u0940 \u0932\u093f\u092f\u093e \u0925\u093e\u0964 \u0932\u0947\u0915\u093f\u0928 \u091a\u0942\u0902\u0915\u093f \u092e\u0941\u091d\u0947 \u0935\u093f\u091c\u094d\u091e\u093e\u0928 (science) \u0914\u0930 \u0917\u0923\u093f\u0924 (mathematics) \u092d\u0940 \u0905\u091a\u094d\u091b\u093e \u0932\u0917\u0924\u093e \u0925\u093e, \u0907\u0938\u0932\u093f\u090f \u0906\u0916\u093f\u0930\u0915\u093e\u0930 \u092e\u0948\u0902\u0928\u0947 \u092d\u094c\u0924\u093f\u0915\u0940 (physics) \u0914\u0930 \u0917\u0923\u093f\u0924 \u0915\u094b \u0906\u0917\u0947 \u092a\u0922\u093c\u093e\u0908 \u0915\u0947 \u0932\u093f\u090f \u091a\u0941\u0928\u093e\u0964 \u0939\u092e\u093e\u0930\u0947 \u0918\u0930 \u092e\u0947\u0902, \u0915\u0949\u0932\u0947\u091c \u0914\u0930 \u092f\u0941\u0928\u093f\u0935\u0930\u094d\u0938\u093f\u091f\u0940 (university) \u091c\u093e\u0928\u093e \u0938\u094d\u0935\u093e\u092d\u093e\u0935\u093f\u0915 \u092c\u093e\u0924 \u0925\u0940\u0964 \u092e\u0948\u0902 \u0905\u092a\u0928\u0940 \u092c\u0940\u090f\u0938\u0938\u0940 (BSc) (\u0911\u0928\u0930\u094d\u0938) \u0914\u0930 \u092e\u093e\u0938\u094d\u091f\u0930\u094d\u0938 \u0921\u093f\u0917\u094d\u0930\u0940 \u0915\u0940 \u092a\u0922\u093c\u093e\u0908 \u0915\u0947 \u0932\u093f\u090f \u092e\u0948\u0938\u0942\u0930 \u0935\u093f\u0936\u094d\u0935\u0935\u093f\u0926\u094d\u092f\u093e\u0932\u092f \u0915\u0947 \u092c\u0948\u0902\u0917\u0932\u094c\u0930 \u0915\u0947 \u0938\u0947\u0902\u091f\u094d\u0930\u0932 \u0915\u0949\u0932\u0947\u091c \u0917\u0908\u0964 \u0907\u0938 \u092a\u0942\u0930\u0940 \u092a\u0922\u093c\u093e\u0908 \u092e\u0947\u0902 \u092e\u0948\u0902\u0928\u0947 \u0939\u092e\u0947\u0936\u093e \u092a\u094d\u0930\u0925\u092e \u0936\u094d\u0930\u0947\u0923\u0940 \u0939\u093e\u0938\u093f\u0932 \u0915\u0940\u0964 \u0914\u0930 \u090f\u092e\u090f\u0938\u0938\u0940 \u0915\u0947 \u092c\u093e\u0926 \u092d\u093e\u0930\u0924\u0940\u092f \u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u0938\u0902\u0938\u094d\u0925\u093e\u0928 (Indian Institute of Science &#8211; IISc), \u092c\u0948\u0902\u0917\u0932\u094c\u0930 \u0915\u0947 \u0924\u0924\u094d\u0915\u093e\u0932\u0940\u0928 \u0935\u093f\u0926\u094d\u092f\u0941\u0924 \u092a\u094d\u0930\u094c\u0926\u094d\u092f\u094b\u0917\u093f\u0915\u0940 \u0935\u093f\u092d\u093e\u0917 \u092e\u0947\u0902 \u0928\u094c\u0915\u0930\u0940 \u0932\u0947 \u0932\u0940\u0964 \u092e\u0948\u0902\u0928\u0947 \u0935\u093f\u0926\u094d\u092f\u0941\u0924 \u0938\u0902\u091a\u093e\u0930 (communication engineering) \u0915\u0947 \u0915\u094d\u0937\u0947\u0924\u094d\u0930 \u092e\u0947\u0902 \u090f\u0915 \u0936\u094b\u0927 \u0938\u0939\u093e\u092f\u0915 \u0915\u0947 \u0930\u0942\u092a \u092e\u0947\u0902 \u0915\u093e\u092e \u0915\u093f\u092f\u093e\u0964<\/p>\n\n\n\n<p>\u0926\u094d\u0935\u093f\u0924\u0940\u092f \u0935\u093f\u0936\u094d\u0935 \u092f\u0941\u0926\u094d\u0927 (World War II) \u0915\u0947 \u092c\u093e\u0926 \u092d\u093e\u0930\u0924 \u092e\u0947\u0902 \u0905\u0902\u0917\u094d\u0930\u0947\u091c\u093c\u094b\u0902 \u0938\u0947 \u092d\u093e\u0930\u0924\u0940\u092f\u094b\u0902 \u0915\u094b \u0938\u0924\u094d\u0924\u093e \u0939\u0938\u094d\u0924\u093e\u0902\u0924\u0930\u093f\u0924 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u090f\u0915 \u0905\u0902\u0924\u0930\u093f\u092e \u0938\u0930\u0915\u093e\u0930 \u0915\u0940 \u0938\u094d\u0925\u093e\u092a\u0928\u093e \u0915\u0940 \u0917\u0908 \u0925\u0940\u0964 \u0907\u0938 \u0938\u0930\u0915\u093e\u0930 \u0928\u0947 \u092a\u094d\u0930\u0924\u093f\u092d\u093e\u0936\u093e\u0932\u0940 \u092f\u0941\u0935\u093e \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 (young scientists) \u0915\u094b \u0935\u093f\u0926\u0947\u0936 \u092e\u0947\u0902 \u0905\u0927\u094d\u092f\u092f\u0928 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u091b\u093e\u0924\u094d\u0930\u0935\u0943\u0924\u094d\u0924\u093f \u092a\u094d\u0930\u0926\u093e\u0928 \u0915\u0940 \u0925\u0940\u0964 \u092e\u0948\u0902\u0928\u0947 \u0907\u0932\u0947\u0915\u094d\u091f\u094d\u0930\u0949\u0928\u093f\u0915\u094d\u0938 (electronics) \u0914\u0930 \u0907\u0938\u0915\u0947 \u0905\u0928\u0941\u092a\u094d\u0930\u092f\u094b\u0917\u094b\u0902 \u0915\u0947 \u0915\u094d\u0937\u0947\u0924\u094d\u0930 \u092e\u0947\u0902 \u0910\u0938\u0940 \u0939\u0940 \u090f\u0915 \u091b\u093e\u0924\u094d\u0930\u0935\u0943\u0924\u094d\u0924\u093f \u0915\u0947 \u0932\u093f\u090f \u0906\u0935\u0947\u0926\u0928 \u0915\u093f\u092f\u093e \u0925\u093e\u0964 1946 \u092e\u0947\u0902 \u0907\u0938 \u091b\u093e\u0924\u094d\u0930\u0935\u0943\u0924\u094d\u0924\u093f \u0915\u0947 \u0932\u093f\u090f \u091a\u092f\u0928\u093f\u0924 \u0939\u094b\u0928\u0947 \u0915\u0947 \u092c\u093e\u0926, \u092e\u0948\u0902 \u0936\u0940\u0918\u094d\u0930 \u0939\u0940 \u0906\u0917\u0947 \u0915\u0940 \u092a\u0922\u093c\u093e\u0908 \u0915\u0947 \u0932\u093f\u090f \u090f\u0928 \u0906\u0930\u094d\u092c\u0930 \u0938\u094d\u0925\u093f\u0924 \u092e\u093f\u0936\u093f\u0917\u0928 \u0935\u093f\u0936\u094d\u0935\u0935\u093f\u0926\u094d\u092f\u093e\u0932\u092f (University of Michigan) \u091a\u0932\u0940 \u0917\u0908\u0964 \u0924\u092c \u092e\u0947\u0930\u0940 \u0909\u092e\u094d\u0930 24-25 \u0915\u0947 \u0906\u0938\u092a\u093e\u0938 \u0939\u0940 \u0925\u0940\u0964 \u0914\u0930 \u0924\u094b \u0914\u0930, \u092e\u0948\u0902 \u0924\u092c \u0905\u0935\u093f\u0935\u093e\u0939\u093f\u0924 \u0925\u0940, \u0932\u0947\u0915\u093f\u0928 \u0924\u092c \u092d\u0940 \u092e\u0947\u0930\u0947 \u092a\u0930\u093f\u0935\u093e\u0930 \u0928\u0947 \u092e\u0947\u0930\u0947 \u0935\u093f\u0926\u0947\u0936 \u091c\u093e\u0928\u0947 \u092a\u0930 \u0915\u094b\u0908 \u0906\u092a\u0924\u094d\u0924\u093f \u0928\u0939\u0940\u0902 \u091c\u0924\u093e\u0908! \u0927\u094d\u092f\u093e\u0928 \u0930\u0939\u0947, \u092f\u0939 \u0906\u091c \u0938\u0947 \u0915\u0930\u0940\u092c 80 \u0938\u093e\u0932 \u092a\u0939\u0932\u0947 \u0915\u0940 \u092c\u093e\u0924 \u0939\u0948! \u0906\u091c \u0915\u0940 \u0915\u0908 \u092f\u0941\u0935\u093e \u0932\u0921\u093c\u0915\u093f\u092f\u093e\u0902 (young women), \u091c\u094b \u0905\u092a\u0928\u0940 \u092a\u0938\u0902\u0926 \u0915\u0947 \u0915\u094b\u0930\u094d\u0938\/\u0935\u093f\u0937\u092f (courses\/subjects) \u0914\u0930 \u0915\u0930\u093f\u092f\u0930 \u091a\u0941\u0928 \u0938\u0915\u0924\u0940 \u0939\u0948\u0902, \u0909\u0928\u094d\u0939\u0947\u0902 \u0936\u093e\u092f\u0926 \u0907\u0938 \u092c\u093e\u0924 \u0915\u093e \u0905\u0902\u0926\u093e\u091c\u093c\u093e \u0928 \u0939\u094b\u0917\u093e \u0915\u093f \u0909\u0938 \u0938\u092e\u092f \u092e\u0939\u093f\u0932\u093e\u0913\u0902 \u0915\u094b \u0915\u093f\u0938 \u0924\u0930\u0939 \u0915\u0947 \u092a\u094d\u0930\u0924\u093f\u092c\u0902\u0927\u094b\u0902 \u0915\u093e \u0938\u093e\u092e\u0928\u093e \u0915\u0930\u0928\u093e \u092a\u0921\u093c\u0924\u093e \u0925\u093e, \u092f\u0939\u093e\u0902 \u0924\u0915 \u0915\u093f \u0935\u093f\u0926\u0947\u0936\u094b\u0902 \u092e\u0947\u0902 \u092d\u0940\u0964 1920 \u092f\u093e 30 \u0915\u0947 \u0926\u0936\u0915 \u0924\u0915 \u092a\u0936\u094d\u091a\u093f\u092e\u0940 \u0926\u0947\u0936\u094b\u0902 \u0915\u0947 \u0915\u0908 \u0935\u093f\u0936\u094d\u0935\u0935\u093f\u0926\u094d\u092f\u093e\u0932\u092f \u092e\u0939\u093f\u0932\u093e\u0913\u0902 \u0915\u094b \u092a\u094d\u0930\u0935\u0947\u0936 \u0928\u0939\u0940\u0902 \u0926\u0947\u0924\u0947 \u0925\u0947\u0964 \u092e\u0948\u0902 \u0935\u093e\u0938\u094d\u0924\u0935 \u092e\u0947\u0902 \u092c\u0939\u0941\u0924 \u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940 \u0925\u0940 \u0915\u093f \u092e\u0941\u091d\u0947 \u0907\u0938 \u0924\u0930\u0939 \u0915\u0947 \u092d\u0947\u0926\u092d\u093e\u0935 \u0915\u093e \u0938\u093e\u092e\u0928\u093e \u0928\u0939\u0940\u0902 \u0915\u0930\u0928\u093e \u092a\u0921\u093c\u093e\u0964<\/p>\n\n\n\n<p>\u0905\u092e\u0947\u0930\u093f\u0915\u093e (United States) \u092e\u0947\u0902 \u0907\u0902\u091c\u0940\u0928\u093f\u092f\u0930\u093f\u0902\u0917 (engineering) \u092e\u0947\u0902 \u092e\u093e\u0938\u094d\u091f\u0930\u094d\u0938 \u0915\u0930\u0928\u093e \u0914\u0930 \u092c\u093e\u0926 \u092e\u0947\u0902 \u092a\u0940\u090f\u091a\u0921\u0940 (PhD) \u0915\u0947 \u0932\u093f\u090f \u0915\u093e\u092e \u0915\u0930\u0928\u093e \u092c\u0939\u0941\u0924 \u0939\u0940 \u0916\u0941\u0936\u0917\u0935\u093e\u0930 \u0930\u0939\u093e, \u0914\u0930 \u0909\u0938 \u0926\u094c\u0930\u093e\u0928 \u092e\u0948\u0902\u0928\u0947 \u0915\u0908 \u091a\u0940\u091c\u093c\u0947\u0902 \u0938\u0940\u0916\u0940\u0902\u0964 \u092e\u0948\u0902\u0928\u0947 \u0914\u0930 \u092d\u0940 \u091c\u093c\u094d\u092f\u093e\u0926\u093e \u0916\u0941\u0932\u0940 \u0938\u094b\u091a \u0930\u0916\u0928\u093e \u0914\u0930 \u0928\u090f \u0935\u093f\u091a\u093e\u0930\u094b\u0902 \u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0917\u094d\u0930\u0939\u0923\u0936\u0940\u0932 \u0939\u094b\u0928\u093e \u0938\u0940\u0916\u093e\u0964 \u092e\u0948\u0902\u0928\u0947 \u0938\u0940\u0916\u093e \u0915\u093f \u0905\u0917\u0930 \u0939\u092e \u092e\u0928 \u092e\u0947\u0902 \u0920\u093e\u0928 \u0932\u0947\u0902 \u0924\u094b \u0915\u0941\u091b \u092d\u0940 \u0939\u093e\u0938\u093f\u0932 \u0915\u0930\u0928\u093e \u0905\u0938\u0902\u092d\u0935 \u0928\u0939\u0940\u0902 \u0939\u0948\u0964 \u092e\u0948\u0902\u0928\u0947 \u0915\u0908 \u0928\u090f \u0926\u094b\u0938\u094d\u0924 \u092c\u0928\u093e\u090f \u0914\u0930 \u0909\u0928\u092e\u0947\u0902 \u0938\u0947 \u0915\u0941\u091b \u0915\u0947 \u0938\u093e\u0925 \u0915\u0908 \u0938\u093e\u0932\u094b\u0902 \u0924\u0915 \u0938\u0902\u092a\u0930\u094d\u0915 \u092c\u0928\u093e\u090f \u0930\u0916\u093e \u0939\u0948\u0964 1949 \u092e\u0947\u0902 \u0905\u092a\u0928\u0940 \u092e\u093e\u0938\u094d\u091f\u0930\u094d\u0938 \u0921\u093f\u0917\u094d\u0930\u0940 \u0939\u093e\u0938\u093f\u0932 \u0915\u0930\u0928\u0947 \u0915\u0947 \u092c\u093e\u0926 \u092e\u0948\u0902 \u0935\u0949\u0936\u093f\u0902\u0917\u091f\u0928 \u0921\u0940\u0938\u0940 \u092e\u0947\u0902 \u0928\u0947\u0936\u0928\u0932 \u092c\u094d\u092f\u0942\u0930\u094b \u0911\u092b \u0938\u094d\u091f\u0948\u0902\u0921\u0930\u094d\u0921\u094d\u0938 \u092e\u0947\u0902 \u0906\u0920 \u092e\u0939\u0940\u0928\u0947 \u0915\u0947 \u0930\u0947\u0921\u093f\u092f\u094b \u092b\u094d\u0930\u0940\u0915\u094d\u0935\u0947\u0902\u0938\u0940 \u092e\u093e\u092a\u0928 \u0915\u0947 \u0935\u094d\u092f\u093e\u0935\u0939\u093e\u0930\u093f\u0915 \u092a\u094d\u0930\u0936\u093f\u0915\u094d\u0937\u0923 \u0915\u0947 \u0932\u093f\u090f \u0917\u0908\u0964 \u0938\u093f\u0924\u0902\u092c\u0930 1949 \u092e\u0947\u0902, \u092e\u0948\u0902 \u092c\u093e\u0930\u092c\u0949\u0930 \u091b\u093e\u0924\u094d\u0930\u0935\u0943\u0924\u094d\u0924\u093f (Barbour Scholarship) \u092a\u0930 \u0905\u092a\u0928\u0940 \u092a\u0940\u090f\u091a\u0921\u0940 \u0915\u0940 \u092a\u0922\u093c\u093e\u0908 \u091c\u093e\u0930\u0940 \u0930\u0916\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u090f\u0928 \u0906\u0930\u094d\u092c\u0930 \u0935\u093e\u092a\u0938 \u0906 \u0917\u0908\u0964 \u0935\u0939\u093e\u0902 \u092e\u0947\u0930\u0947 \u0938\u0932\u093e\u0939\u0915\u093e\u0930 \u092a\u094d\u0930\u094b\u092b\u0947\u0938\u0930 \u0935\u093f\u0932\u093f\u092f\u092e \u091c\u0940. \u0921\u0949\u0935 \u0925\u0947, \u091c\u093f\u0928\u0915\u093e 1999 \u092e\u0947\u0902 103 \u0935\u0930\u094d\u0937 \u0915\u0940 \u0906\u092f\u0941 \u092e\u0947\u0902 \u0928\u093f\u0927\u0928 \u0939\u094b \u0917\u092f\u093e\u0964<\/p>\n\n\n\n<p>1953 \u092e\u0947\u0902 \u092e\u0948\u0902 \u092d\u093e\u0930\u0924 \u0932\u094c\u091f\u0940\u0964 \u092f\u0939\u093e\u0902 \u0906\u0915\u0930 \u092e\u0948\u0902 \u092d\u093e\u0930\u0924\u0940\u092f \u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u0938\u0902\u0938\u094d\u0925\u093e\u0928 (IISc) \u092e\u0947\u0902 \u0936\u093e\u092e\u093f\u0932 \u0939\u094b \u0917\u0908, \u0914\u0930 \u090f\u0915 \u0938\u0915\u094d\u0930\u093f\u092f \u0936\u094b\u0927 \u0915\u0930\u093f\u092f\u0930 \u0936\u0941\u0930\u0942 \u0915\u093f\u092f\u093e\u0964 \u0905\u092a\u0928\u0947 \u092a\u0930\u093f\u0935\u093e\u0930 \u0915\u0947 \u092a\u0942\u0930\u094d\u0923 \u0938\u092e\u0930\u094d\u0925\u0928 \u0915\u0947 \u0938\u093e\u0925, \u092e\u0948\u0902\u0928\u0947 \u0905\u092a\u0928\u0947 \u090f\u0915 \u0938\u0939\u0915\u0930\u094d\u092e\u0940 \u0936\u093f\u0936\u093f\u0930 \u0915\u0941\u092e\u093e\u0930 \u091a\u091f\u0930\u094d\u091c\u0940 \u0938\u0947 \u0935\u093f\u0935\u093e\u0939 \u0915\u093f\u092f\u093e, \u0914\u0930 \u0915\u0908 \u092a\u094d\u0930\u094b\u091c\u0947\u0915\u094d\u091f \u092a\u0930 \u0909\u0928\u0915\u0947 \u0938\u093e\u0925 \u092e\u093f\u0932\u0915\u0930 \u0915\u093e\u092e \u092d\u0940 \u0915\u093f\u092f\u093e\u0964 \u0939\u092e\u0928\u0947 \u0905\u092a\u0928\u093e \u0905\u0927\u093f\u0915\u093e\u0902\u0936 \u0938\u092e\u092f IISc \u0915\u0947 \u0916\u0942\u092c\u0938\u0942\u0930\u0924 \u092e\u093e\u0939\u094c\u0932 \u092e\u0947\u0902 \u092c\u093f\u0924\u093e\u092f\u093e &#8211; \u092f\u093e \u0924\u094b \u0935\u093f\u092d\u093e\u0917 \u092e\u0947\u0902 \u092f\u093e \u0932\u093e\u092f\u092c\u094d\u0930\u0947\u0930\u0940 \u092e\u0947\u0902\u0964 \u0939\u092e\u093e\u0930\u0940 \u092c\u0947\u091f\u0940, \u091c\u094b \u0905\u092c \u0905\u092e\u0947\u0930\u093f\u0915\u093e \u092e\u0947\u0902 \u092a\u094d\u0930\u094b\u092b\u0947\u0938\u0930 (professor in the US) \u0939\u0948, \u0928\u0947 \u0905\u092a\u0928\u093e \u092a\u0942\u0930\u093e \u092c\u091a\u092a\u0928 \u092f\u0939\u0940\u0902 \u092c\u093f\u0924\u093e\u092f\u093e\u0964<\/p>\n\n\n\n<p>\u092e\u0947\u0930\u0947 \u092a\u0924\u093f \u0914\u0930 \u092e\u0948\u0902, \u0939\u092e \u0926\u094b\u0928\u094b\u0902 \u0915\u0908 \u092a\u094d\u0930\u094b\u091c\u0947\u0915\u094d\u091f \u0932\u0947\u0924\u0947 \u0925\u0947 \u0914\u0930 \u0939\u092e\u0928\u0947 \u0938\u0902\u092f\u0941\u0915\u094d\u0924 \u0930\u0942\u092a \u0938\u0947 \u0915\u0908 \u0936\u094b\u0927\u092a\u0924\u094d\u0930 (research papers) \u092a\u094d\u0930\u0915\u093e\u0936\u093f\u0924 \u0915\u093f\u090f\u0964 \u0939\u092e\u0928\u0947 \u0915\u0908 \u0915\u094b\u0930\u094d\u0938\u0947\u0938, \u091c\u093c\u094d\u092f\u093e\u0926\u093e\u0924\u0930 \u0935\u093f\u0926\u094d\u092f\u0941\u0924 \u091a\u0941\u0902\u092c\u0915\u0940\u092f \u0938\u093f\u0926\u094d\u0927\u093e\u0902\u0924, \u0907\u0932\u0947\u0915\u094d\u091f\u094d\u0930\u0949\u0928 \u091f\u094d\u092f\u0942\u092c \u0938\u0930\u094d\u0915\u093f\u091f(electron tube circuits), &nbsp;\u092e\u093e\u0907\u0915\u094d\u0930\u094b\u0935\u0947\u0935 \u0924\u0915\u0928\u0940\u0915(microwave technology) \u0914\u0930 \u0930\u0947\u0921\u093f\u092f\u094b \u0907\u0902\u091c\u0940\u0928\u093f\u092f\u0930\u093f\u0902\u0917 (radio engineering) &nbsp;\u0915\u0947 \u092a\u0922\u093c\u093e\u090f \u0914\u0930 \u0907\u0928 \u092a\u0930 \u0915\u0908 \u0915\u093f\u0924\u093e\u092c\u0947\u0902 \u092d\u0940 \u0932\u093f\u0916\u0940\u0902\u0964 \u092e\u0947\u0930\u093e \u092e\u0941\u0916\u094d\u092f \u092f\u094b\u0917\u0926\u093e\u0928 \u092e\u0941\u0916\u094d\u092f\u0924: \u0935\u093f\u092e\u093e\u0928 \u0914\u0930 \u0905\u0902\u0924\u0930\u093f\u0915\u094d\u0937 \u092f\u093e\u0928(aircraft and spacecraft), \u092e\u0947\u0902 \u0909\u092a\u092f\u094b\u0917 \u0915\u093f\u090f \u091c\u093e\u0928\u0947 \u0935\u093e\u0932\u0947 \u090f\u0902\u091f\u0940\u0928\u093e(antennas) &nbsp;\\ \u0915\u0947 \u0915\u094d\u0937\u0947\u0924\u094d\u0930 \u092e\u0947\u0902 \u0930\u0939\u093e \u0939\u0948\u0964 1994 \u092e\u0947\u0902 \u0936\u093f\u0936\u093f\u0930 \u0915\u0947 \u0928\u093f\u0927\u0928 \u0915\u0947 \u092c\u093e\u0926 \u092d\u0940 \u092e\u0948\u0902\u0928\u0947 \u0907\u0928 \u0935\u093f\u0937\u092f\u094b\u0902 \u092a\u0930 \u0915\u093f\u0924\u093e\u092c\u0947\u0902 \u0932\u093f\u0916\u0928\u093e \u091c\u093e\u0930\u0940 \u0930\u0916\u093e, \u0914\u0930 \u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u0924\u0925\u093e \u0935\u093f\u0936\u0947\u0937 \u0930\u0942\u092a \u0938\u0947 \u0907\u0902\u091c\u0940\u0928\u093f\u092f\u0930\u093f\u0902\u0917 \u092e\u0947\u0902 \u0905\u092a\u0928\u0940 \u0930\u0941\u091a\u093f \u092c\u0928\u093e\u090f \u0930\u0916\u0940\u0964 \u092e\u0948\u0902\u0928\u0947 20 \u092a\u0940\u090f\u091a\u0921\u0940 \u091b\u093e\u0924\u094d\u0930 \u0914\u0930 \u091b\u093e\u0924\u094d\u0930\u093e\u0913\u0902 \u0915\u094b \u0909\u0928\u0915\u0947 \u0915\u093e\u092e \u092e\u0947\u0902 \u092e\u093e\u0930\u094d\u0917\u0926\u0930\u094d\u0936\u0928 \u0926\u093f\u092f\u093e\u0964 \u092e\u0947\u0930\u0947 \u0915\u0908 \u091b\u093e\u0924\u094d\u0930-\u091b\u093e\u0924\u094d\u0930\u093e\u090f\u0902 \u0905\u092a\u0928\u0947-\u0905\u092a\u0928\u0947 \u0915\u094d\u0937\u0947\u0924\u094d\u0930\u094b\u0902 \u092e\u0947\u0902 \u092a\u094d\u0930\u0938\u093f\u0926\u094d\u0927 \u0939\u0941\u090f \u0939\u0948\u0902, \u0914\u0930 \u092d\u093e\u0930\u0924 \u0914\u0930 \u0935\u093f\u0926\u0947\u0936\u094b\u0902 \u092e\u0947\u0902 \u0921\u093e\u092f\u0930\u0947\u0915\u094d\u091f\u0930 \u0914\u0930 \u092a\u094d\u0930\u094b\u092b\u0947\u0938\u0930 \u092c\u0928\u0947\u0964<\/p>\n\n\n\n<p>\u0915\u0908 \u092a\u0941\u0930\u0938\u094d\u0915\u093e\u0930 \u0914\u0930 \u0938\u092e\u094d\u092e\u093e\u0928 \u092e\u0941\u091d\u0947 \u092e\u093f\u0932\u0947 \u0939\u0948\u0902\u0964 \u0907\u0928\u092e\u0947\u0902 \u092c\u0940\u090f\u0938\u0938\u0940 (\u0911\u0928\u0930\u094d\u0938) \u092e\u0947\u0902 \u092a\u094d\u0930\u0925\u092e \u0930\u0948\u0902\u0915 \u0915\u0947 \u0932\u093f\u090f \u092e\u0941\u092e\u094d\u092e\u0926\u0940 \u0915\u0943\u0937\u094d\u0923\u0930\u093e\u091c \u0935\u094b\u0921\u0947\u092f\u093e\u0930 \u092a\u0941\u0930\u0938\u094d\u0915\u093e\u0930, \u090f\u092e\u090f\u0938\u0938\u0940 \u092e\u0947\u0902 \u092a\u094d\u0930\u0925\u092e \u0930\u0948\u0902\u0915 \u0915\u0947 \u0932\u093f\u090f \u090f\u092e. \u091f\u0940. \u0928\u093e\u0930\u093e\u092f\u0923 \u0905\u092f\u0902\u0917\u0930 \u092a\u0941\u0930\u0938\u094d\u0915\u093e\u0930 \u090f\u0935\u0902 \u0935\u0949\u091f\u0930\u094d\u0938 \u092e\u0947\u092e\u094b\u0930\u093f\u092f\u0932 \u092a\u0941\u0930\u0938\u094d\u0915\u093e\u0930, \u0907\u0902\u0938\u094d\u091f\u0940\u091f\u094d\u092f\u0942\u091f \u0911\u092b \u0907\u0932\u0947\u0915\u094d\u091f\u094d\u0930\u093f\u0915\u0932 \u090f\u0902\u0921 \u0930\u0947\u0921\u093f\u092f\u094b \u0907\u0902\u091c\u0940\u0928\u093f\u092f\u0930\u093f\u0902\u0917, \u092f\u0942\u0915\u0947 \u0938\u0947 \u0938\u0930\u094d\u0935\u0936\u094d\u0930\u0947\u0937\u094d\u0920 \u092a\u0947\u092a\u0930 \u0915\u0947 \u0932\u093f\u090f \u0932\u0949\u0930\u094d\u0921 \u092e\u093e\u0909\u0902\u091f\u092c\u0947\u091f\u0928 \u092a\u0941\u0930\u0938\u094d\u0915\u093e\u0930(Lord Mountbatten Award), \u0907\u0902\u0938\u094d\u091f\u0940\u091f\u094d\u092f\u0942\u0936\u0928 \u0911\u092b \u0907\u0902\u091c\u0940\u0928\u093f\u092f\u0930\u094d\u0938 \u0938\u0947 \u0938\u0930\u094d\u0935\u0936\u094d\u0930\u0947\u0937\u094d\u0920 \u0936\u094b\u0927 \u092a\u0924\u094d\u0930 \u0915\u0947 \u0932\u093f\u090f \u091c\u0947. \u0938\u0940. \u092c\u094b\u0938 \u092e\u0947\u092e\u094b\u0930\u093f\u092f\u0932 \u092a\u0941\u0930\u0938\u094d\u0915\u093e\u0930 \u0914\u0930 \u0907\u0902\u0938\u094d\u091f\u0940\u091f\u094d\u092f\u0942\u091f \u0911\u092b \u0907\u0932\u0947\u0915\u094d\u091f\u094d\u0930\u0949\u0928\u093f\u0915\u094d\u0938 \u090f\u0902\u0921 \u091f\u0947\u0932\u0940\u0915\u092e\u094d\u092f\u0942\u0928\u093f\u0915\u0947\u0936\u0928 \u0907\u0902\u091c\u0940\u0928\u093f\u092f\u0930\u094d\u0938 \u0915\u0947 \u0938\u0930\u094d\u0935\u0936\u094d\u0930\u0947\u0937\u094d\u0920 \u0936\u094b\u0927 \u0914\u0930 \u0936\u093f\u0915\u094d\u0937\u0923 \u0915\u093e\u0930\u094d\u092f \u0915\u0947 \u0932\u093f\u090f \u0930\u093e\u092e\u0932\u093e\u0932 \u0935\u093e\u0927\u0935\u093e \u092a\u0941\u0930\u0938\u094d\u0915\u093e\u0930 \u0936\u093e\u092e\u093f\u0932 \u0939\u0948\u0902\u0964 \u0907\u0928 \u0938\u092c\u0938\u0947 \u092c\u0922\u093c\u0915\u0930, \u092e\u0948\u0902\u0928\u0947 \u0905\u092a\u0928\u0947 \u0915\u0941\u091b \u091b\u093e\u0924\u094d\u0930-\u091b\u093e\u0924\u094d\u0930\u093e\u0913\u0902 \u0914\u0930 \u0915\u0908 \u092f\u0941\u0935\u093e\u0913\u0902 \u0915\u093e \u0938\u093e\u0925 \u0914\u0930 \u0938\u094d\u0928\u0947\u0939 \u0915\u092e\u093e\u092f\u093e \u0939\u0948\u0964 \u092e\u0948\u0902\u0928\u0947 \u0907\u0928 \u0938\u092d\u0940 \u0938\u0947 \u092c\u0939\u0941\u0924 \u0915\u0941\u091b \u0938\u0940\u0916\u093e \u0939\u0948, \u092e\u0947\u0930\u0947 \u0915\u0908 \u0935\u093f\u091a\u093e\u0930\u094b\u0902 \u092e\u0947\u0902 \u092c\u0921\u093c\u0947-\u092c\u0921\u093c\u0947 \u092c\u0926\u0932\u093e\u0935 \u0906\u090f \u0939\u0948\u0902!<\/p>\n\n\n\n<p>IISc \u0938\u0947 \u0930\u093f\u091f\u093e\u092f\u0930\u092e\u0947\u0902\u091f \u0915\u0947 \u092c\u093e\u0926, \u092e\u0948\u0902\u0928\u0947 \u0938\u093e\u092e\u093e\u091c\u093f\u0915 \u0915\u093e\u0930\u094d\u092f\u0915\u094d\u0930\u092e\u094b\u0902 \u092a\u0930 \u0915\u093e\u092e \u0915\u0930\u0928\u093e \u0936\u0941\u0930\u0942 \u0915\u093f\u092f\u093e, \u092e\u0941\u0916\u094d\u092f\u0924: \u0907\u0902\u0921\u093f\u092f\u0928 \u090f\u0938\u094b\u0938\u093f\u090f\u0936\u0928 \u092b\u0949\u0930 \u0935\u0940\u092e\u0928\u094d\u0938 \u0938\u094d\u091f\u0921\u0940\u091c\u093c (Indian Association for Women&#8217;s Studies) \u0915\u0947 \u0938\u093e\u0925\u0964 \u0924\u092c \u092e\u0948\u0902\u0928\u0947 \u091c\u093e\u0928\u093e \u0915\u093f \u0915\u093f\u0924\u0928\u0940 \u092e\u0939\u093f\u0932\u093e\u0913\u0902 \u0928\u0947 \u091c\u0940\u0935\u0928 \u092e\u0947\u0902 \u0906\u0917\u0947 \u092c\u0922\u093c\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0924\u092e\u093e\u092e \u092c\u093e\u0927\u093e\u0913\u0902 \u0915\u0947 \u092c\u093e\u0935\u091c\u0942\u0926 \u0915\u093f\u0924\u0928\u093e \u0938\u0902\u0918\u0930\u094d\u0937 \u0915\u093f\u092f\u093e \u0939\u0948, \u091c\u093f\u0928\u0915\u093e \u0938\u093e\u092e\u0928\u093e \u0939\u092e \u091c\u0948\u0938\u0947 \u0915\u0941\u0932\u0940\u0928 \u0935\u0930\u094d\u0917 \u0915\u0947 \u0932\u094b\u0917\u094b\u0902 \u0915\u094b \u0936\u093e\u092f\u0926 \u0939\u0940 \u0915\u092d\u0940 \u0915\u0930\u0928\u093e \u092a\u0921\u093c\u093e \u0939\u094b\u0964 \u092e\u0947\u0930\u093e \u092e\u093e\u0928\u0928\u093e \u0939\u0948 \u0915\u093f \u0939\u092e \u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940 \u0925\u0947 \u0924\u094b \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u0914\u0930 \u0907\u0902\u091c\u0940\u0928\u093f\u092f\u0930 \u0915\u093e \u092f\u0939 \u092e\u0915\u093e\u092e \u0939\u092e\u0928\u0947 \u0939\u093e\u0938\u093f\u0932 \u0915\u093f\u092f\u093e\u0964 \u0914\u0930 \u0910\u0938\u0947\u00a0 \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u0914\u0930 \u0907\u0902\u091c\u0940\u0928\u093f\u092f\u0930 \u0939\u094b\u0928\u0947 \u0915\u0947 \u0928\u093e\u0924\u0947 \u0939\u092e\u0947\u0902 \u0905\u092a\u0928\u0947 \u0938\u0947 \u0915\u092e \u0938\u0941\u0935\u093f\u0927\u093e \u092a\u094d\u0930\u093e\u092a\u094d\u0924 \u0932\u094b\u0917\u094b\u0902 \u0915\u0940, \u0916\u093e\u0938\u0915\u0930 \u092e\u0939\u093f\u0932\u093e\u0913\u0902 \u0915\u0940, \u0905\u092a\u0928\u0947 \u092a\u0938\u0902\u0926\u0940\u0926\u093e \u0935\u093f\u0937\u092f \u092e\u0947\u0902 \u0905\u0927\u094d\u092f\u092f\u0928 \u0915\u0930\u0928\u0947, \u0915\u093e\u092e \u0915\u0930\u0928\u0947 \u0914\u0930 \u0906\u0917\u0947 \u092c\u0922\u093c\u0928\u0947 \u092e\u0947\u0902 \u0939\u0930 \u0938\u0902\u092d\u0935 \u092e\u0926\u0926 \u0915\u0930\u0928\u093e \u091a\u093e\u0939\u093f\u090f\u0964 <strong><em>(\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938)<\/em><\/strong><\/p>\n\n\n\n<p>\u0928\u094b\u091f: \u0938\u094d\u0930\u094b\u0924 \u092e\u0947\u0902 \u091b\u092a\u0947 \u0932\u0947\u0916\u094b\u0902 \u0915\u0947 \u0935\u093f\u091a\u093e\u0930 \u0932\u0947\u0916\u0915\u094b\u0902 \u0915\u0947 \u0939\u0948\u0902\u0964 \u090f\u0915\u0932\u0935\u094d\u092f \u0915\u093e \u0907\u0928\u0938\u0947 \u0938\u0939\u092e\u0924 \u0939\u094b\u0928\u093e \u0906\u0935\u0936\u094d\u092f\u0915 \u0928\u0939\u0940\u0902 \u0939\u0948\u0964<br>Photo Credit : https:\/\/upload.wikimedia.org\/wikipedia\/en\/4\/42\/Rajeshwari_Chatterjee_image.jpg<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0938\u0902\u0915\u0932\u0928: \u0915\u0947. \u0936\u0936\u093f\u0915\u0932\u093e \u092e\u0939\u093f\u0932\u093e \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0915\u0940 \u092c\u093e\u0924 \u0915\u0930\u0947\u0902 \u0924\u094b \u0907\u0915\u094d\u0915\u093e&#8211;\u0926\u0941\u0915\u094d\u0915\u093e \u0928\u093e\u092e \u0939\u0940 \u0938\u093e\u092e\u0928\u0947 \u0906\u0924\u0947 \u0939\u0948\u0902\u0964 \u090f\u0915 \u0915\u093e\u0930\u0923 \u0939\u0948 \u0915\u093f \u0938\u093e\u092e\u093e\u091c\u093f\u0915 \u0905\u0938\u092e\u093e\u0928\u0924\u093e\u0913\u0902 \u0914\u0930 \u0930\u0942\u0922\u093c\u093f\u0935\u093e\u0926\u0940 \u092e\u093e\u0928\u094d\u092f\u0924\u093e\u0913\u0902 \u0915\u0947 \u091a\u0932\u0924\u0947 \u092c\u0939\u0941\u0924 \u0915\u092e \u092e\u0939\u093f\u0932\u093e\u090f\u0902 \u0909\u091a\u094d\u091a \u0936\u093f\u0915\u094d\u0937\u093e \u0939\u093e\u0938\u093f\u0932 \u0915\u0930 \u092a\u093e\u0924\u0940 \u0939\u0948\u0902, \u0935\u0939 \u092d\u0940 \u0905\u0915\u094d\u0938\u0930 \u0924\u092e\u093e\u092e \u0938\u0902\u0918\u0930\u094d\u0937\u094b\u0902 \u0938\u0947 \u0917\u0941\u091c\u093c\u0930\u0924\u0947 \u0939\u0941\u090f\u0964 \u0926\u0942\u0938\u0930\u093e \u0915\u093e\u0930\u0923 \u092f\u0939 \u0939\u0948 \u0915\u093f \u091c\u094b \u092e\u0939\u093f\u0932\u093e\u090f\u0902 \u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u092e\u0947\u0902 \u0936\u094b\u0927\u0930\u0924 \u0939\u0948\u0902, \u0909\u0928\u0915\u0947 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/\" class=\"more-link\">\u092a\u0922\u093c\u0928\u093e \u091c\u093e\u0930\u0940 \u0930\u0916\u0947\u0902<span class=\"screen-reader-text\"> &#8220;\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-5939","post","type-post","status-publish","format-standard","hentry","category-25"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940 - \u0938\u094d\u0930\u094b\u0924<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940-\u0925\u0940-\u0924\u094b-\u092f\u0939-\u092e\u0915\u093e\/\" \/>\n<meta property=\"og:locale\" content=\"hi_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940 - \u0938\u094d\u0930\u094b\u0924\" \/>\n<meta property=\"og:description\" content=\"\u0938\u0902\u0915\u0932\u0928: \u0915\u0947. \u0936\u0936\u093f\u0915\u0932\u093e \u092e\u0939\u093f\u0932\u093e \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0915\u0940 \u092c\u093e\u0924 \u0915\u0930\u0947\u0902 \u0924\u094b \u0907\u0915\u094d\u0915\u093e&#8211;\u0926\u0941\u0915\u094d\u0915\u093e \u0928\u093e\u092e \u0939\u0940 \u0938\u093e\u092e\u0928\u0947 \u0906\u0924\u0947 \u0939\u0948\u0902\u0964 \u090f\u0915 \u0915\u093e\u0930\u0923 \u0939\u0948 \u0915\u093f \u0938\u093e\u092e\u093e\u091c\u093f\u0915 \u0905\u0938\u092e\u093e\u0928\u0924\u093e\u0913\u0902 \u0914\u0930 \u0930\u0942\u0922\u093c\u093f\u0935\u093e\u0926\u0940 \u092e\u093e\u0928\u094d\u092f\u0924\u093e\u0913\u0902 \u0915\u0947 \u091a\u0932\u0924\u0947 \u092c\u0939\u0941\u0924 \u0915\u092e \u092e\u0939\u093f\u0932\u093e\u090f\u0902 \u0909\u091a\u094d\u091a \u0936\u093f\u0915\u094d\u0937\u093e \u0939\u093e\u0938\u093f\u0932 \u0915\u0930 \u092a\u093e\u0924\u0940 \u0939\u0948\u0902, \u0935\u0939 \u092d\u0940 \u0905\u0915\u094d\u0938\u0930 \u0924\u092e\u093e\u092e \u0938\u0902\u0918\u0930\u094d\u0937\u094b\u0902 \u0938\u0947 \u0917\u0941\u091c\u093c\u0930\u0924\u0947 \u0939\u0941\u090f\u0964 \u0926\u0942\u0938\u0930\u093e \u0915\u093e\u0930\u0923 \u092f\u0939 \u0939\u0948 \u0915\u093f \u091c\u094b \u092e\u0939\u093f\u0932\u093e\u090f\u0902 \u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u092e\u0947\u0902 \u0936\u094b\u0927\u0930\u0924 \u0939\u0948\u0902, \u0909\u0928\u0915\u0947 &hellip; \u092a\u0922\u093c\u0928\u093e \u091c\u093e\u0930\u0940 \u0930\u0916\u0947\u0902 &quot;\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940-\u0925\u0940-\u0924\u094b-\u092f\u0939-\u092e\u0915\u093e\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0938\u094d\u0930\u094b\u0924\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-20T03:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg\" \/>\n<meta name=\"author\" content=\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/\"},\"author\":{\"name\":\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab\"},\"headline\":\"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940\",\"datePublished\":\"2024-11-20T03:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/\"},\"wordCount\":95,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg\",\"articleSection\":[\"\u091c\u0940\u0935\u0928\u0940\"],\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/\",\"url\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/\",\"name\":\"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940 - \u0938\u094d\u0930\u094b\u0924\",\"isPartOf\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg\",\"datePublished\":\"2024-11-20T03:30:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#breadcrumb\"},\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#primaryimage\",\"url\":\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg\",\"contentUrl\":\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg\",\"width\":282,\"height\":352},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.srotefeatures.in\/srote\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#website\",\"url\":\"https:\/\/www.srotefeatures.in\/srote\/\",\"name\":\"\u0938\u094d\u0930\u094b\u0924\",\"description\":\"\u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u090f\u0935\u0902 \u091f\u0947\u0915\u094d\u0928\u0949\u0932\u0949\u091c\u0940 \u092b\u0940\u091a\u0930\u094d\u0938\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.srotefeatures.in\/srote\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hi-IN\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab\",\"name\":\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g\",\"caption\":\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\"},\"url\":\"https:\/\/www.srotefeatures.in\/srote\/author\/srote\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940 - \u0938\u094d\u0930\u094b\u0924","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940-\u0925\u0940-\u0924\u094b-\u092f\u0939-\u092e\u0915\u093e\/","og_locale":"hi_IN","og_type":"article","og_title":"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940 - \u0938\u094d\u0930\u094b\u0924","og_description":"\u0938\u0902\u0915\u0932\u0928: \u0915\u0947. \u0936\u0936\u093f\u0915\u0932\u093e \u092e\u0939\u093f\u0932\u093e \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0915\u0940 \u092c\u093e\u0924 \u0915\u0930\u0947\u0902 \u0924\u094b \u0907\u0915\u094d\u0915\u093e&#8211;\u0926\u0941\u0915\u094d\u0915\u093e \u0928\u093e\u092e \u0939\u0940 \u0938\u093e\u092e\u0928\u0947 \u0906\u0924\u0947 \u0939\u0948\u0902\u0964 \u090f\u0915 \u0915\u093e\u0930\u0923 \u0939\u0948 \u0915\u093f \u0938\u093e\u092e\u093e\u091c\u093f\u0915 \u0905\u0938\u092e\u093e\u0928\u0924\u093e\u0913\u0902 \u0914\u0930 \u0930\u0942\u0922\u093c\u093f\u0935\u093e\u0926\u0940 \u092e\u093e\u0928\u094d\u092f\u0924\u093e\u0913\u0902 \u0915\u0947 \u091a\u0932\u0924\u0947 \u092c\u0939\u0941\u0924 \u0915\u092e \u092e\u0939\u093f\u0932\u093e\u090f\u0902 \u0909\u091a\u094d\u091a \u0936\u093f\u0915\u094d\u0937\u093e \u0939\u093e\u0938\u093f\u0932 \u0915\u0930 \u092a\u093e\u0924\u0940 \u0939\u0948\u0902, \u0935\u0939 \u092d\u0940 \u0905\u0915\u094d\u0938\u0930 \u0924\u092e\u093e\u092e \u0938\u0902\u0918\u0930\u094d\u0937\u094b\u0902 \u0938\u0947 \u0917\u0941\u091c\u093c\u0930\u0924\u0947 \u0939\u0941\u090f\u0964 \u0926\u0942\u0938\u0930\u093e \u0915\u093e\u0930\u0923 \u092f\u0939 \u0939\u0948 \u0915\u093f \u091c\u094b \u092e\u0939\u093f\u0932\u093e\u090f\u0902 \u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u092e\u0947\u0902 \u0936\u094b\u0927\u0930\u0924 \u0939\u0948\u0902, \u0909\u0928\u0915\u0947 &hellip; \u092a\u0922\u093c\u0928\u093e \u091c\u093e\u0930\u0940 \u0930\u0916\u0947\u0902 \"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940\"","og_url":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940-\u0925\u0940-\u0924\u094b-\u092f\u0939-\u092e\u0915\u093e\/","og_site_name":"\u0938\u094d\u0930\u094b\u0924","article_published_time":"2024-11-20T03:30:00+00:00","og_image":[{"url":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg","type":"","width":"","height":""}],"author":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938","twitter_card":"summary_large_image","twitter_misc":{"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#article","isPartOf":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/"},"author":{"name":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938","@id":"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab"},"headline":"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940","datePublished":"2024-11-20T03:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/"},"wordCount":95,"commentCount":0,"image":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#primaryimage"},"thumbnailUrl":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg","articleSection":["\u091c\u0940\u0935\u0928\u0940"],"inLanguage":"hi-IN","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/","url":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/","name":"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940 - \u0938\u094d\u0930\u094b\u0924","isPartOf":{"@id":"https:\/\/www.srotefeatures.in\/srote\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#primaryimage"},"image":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#primaryimage"},"thumbnailUrl":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg","datePublished":"2024-11-20T03:30:00+00:00","author":{"@id":"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab"},"breadcrumb":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#breadcrumb"},"inLanguage":"hi-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/"]}]},{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#primaryimage","url":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg","contentUrl":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2024\/11\/Rajeshwari_Chatterjee.jpg","width":282,"height":352},{"@type":"BreadcrumbList","@id":"https:\/\/www.srotefeatures.in\/srote\/2024\/11\/%e0%a4%b8%e0%a5%8c%e0%a4%ad%e0%a4%be%e0%a4%97%e0%a5%8d%e0%a4%af%e0%a4%b6%e0%a4%be%e0%a4%b2%e0%a5%80-%e0%a4%a5%e0%a5%80-%e0%a4%a4%e0%a5%8b-%e0%a4%af%e0%a4%b9-%e0%a4%ae%e0%a4%95%e0%a4%be\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.srotefeatures.in\/srote\/"},{"@type":"ListItem","position":2,"name":"\u0938\u094c\u092d\u093e\u0917\u094d\u092f\u0936\u093e\u0932\u0940\u00a0\u0925\u0940, \u0924\u094b\u00a0\u092f\u0939\u00a0\u092e\u0915\u093e\u092e\u00a0\u092a\u093e\u092f\u093e: \u0930\u093e\u091c\u0947\u0936\u094d\u0935\u0930\u0940\u00a0\u091a\u091f\u0930\u094d\u091c\u0940"}]},{"@type":"WebSite","@id":"https:\/\/www.srotefeatures.in\/srote\/#website","url":"https:\/\/www.srotefeatures.in\/srote\/","name":"\u0938\u094d\u0930\u094b\u0924","description":"\u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u090f\u0935\u0902 \u091f\u0947\u0915\u094d\u0928\u0949\u0932\u0949\u091c\u0940 \u092b\u0940\u091a\u0930\u094d\u0938","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.srotefeatures.in\/srote\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hi-IN"},{"@type":"Person","@id":"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab","name":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938","image":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g","caption":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938"},"url":"https:\/\/www.srotefeatures.in\/srote\/author\/srote\/"}]}},"_links":{"self":[{"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/posts\/5939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/comments?post=5939"}],"version-history":[{"count":1,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/posts\/5939\/revisions"}],"predecessor-version":[{"id":5941,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/posts\/5939\/revisions\/5941"}],"wp:attachment":[{"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/media?parent=5939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/categories?post=5939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/tags?post=5939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}