{"id":7409,"date":"2026-07-15T12:31:01","date_gmt":"2026-07-15T07:01:01","guid":{"rendered":"https:\/\/www.srotefeatures.in\/srote\/?p=7409"},"modified":"2026-07-29T15:49:36","modified_gmt":"2026-07-29T10:19:36","slug":"%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d","status":"publish","type":"post","link":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/","title":{"rendered":"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902?"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"928\" height=\"555\" data-id=\"7426\" src=\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg\" alt=\"\" class=\"wp-image-7426\" srcset=\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg 928w, https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath--300x179.jpg 300w, https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath--768x459.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><strong>\u092e<\/strong>\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u0915\u094b \u0938\u093e\u0925\u093f\u092f\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0930\u0939\u0928\u093e \u092a\u0938\u0902\u0926 \u0939\u0948\u0964 \u0915\u094d\u092f\u093e \u0907\u0938\u0915\u0947 \u092a\u0940\u091b\u0947 \u0915\u094b\u0908 \u091c\u0940\u0935 \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u0915\u093e\u0930\u0923 \u0939\u0948?&nbsp;&nbsp; \u0907\u0938\u0947 \u0938\u092e\u091d\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0928\u0947 \u091c\u093e\u0928\u0935\u0930\u094b\u0902 \u0914\u0930 \u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u092a\u0930 \u0915\u0941\u091b \u0926\u093f\u0932\u091a\u0938\u094d\u092a \u0905\u0927\u094d\u092f\u092f\u0928 \u0915\u093f\u090f \u0939\u0948\u0902\u0964 \u0905\u0927\u094d\u092f\u092f\u0928 \u092c\u0924\u093e\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0938\u092e\u0942\u0939 \u092e\u0947\u0902 \u0930\u0939\u0928\u093e, \u092e\u093f\u0932\u0928\u093e-\u091c\u0941\u0932\u0928\u093e \u0915\u0947\u0935\u0932 \u092a\u0938\u0902\u0926 -\u0928\u093e\u092a\u0938\u0902\u0926 \u092e\u093e\u092e\u0932\u093e \u0928\u0939\u0940\u0902 \u0939\u0948 \u092c\u0932\u094d\u0915\u093f \u0930\u094b\u091f\u0940-\u0915\u092a\u0921\u093c\u093e-\u092e\u0915\u093e\u0928 \u0915\u0940 \u0924\u0930\u0939 \u092f\u0939 \u092d\u0940 \u0939\u092e\u093e\u0930\u0947 \u091c\u0940\u0935\u0928 \u0915\u093e \u0906\u0927\u093e\u0930 \u0914\u0930 \u092e\u0942\u0932 \u091c\u093c\u0930\u0942\u0930\u0924 \u0939\u0948\u0964&nbsp;<\/p>\n\n\n\n<p>\u0924\u0902\u0924\u094d\u0930\u093f\u0915\u093e \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u091a\u0942\u0939\u094b\u0902 \u0914\u0930 \u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u0915\u0947 \u092e\u0938\u094d\u0924\u093f\u0937\u094d\u0915 \u092a\u0930 \u0936\u094b\u0927 \u0915\u0930\u0915\u0947 \u092f\u0939 \u0938\u092e\u091d\u0928\u0947 \u0915\u0940 \u0915\u094b\u0936\u093f\u0936 \u0915\u0930\u0928\u0947 \u092e\u0947\u0902 \u091c\u0941\u091f\u0947 \u0939\u0948\u0902 \u0915\u093f \u2018\u0905\u0915\u0947\u0932\u093e\u092a\u0928 \u0926\u0941\u0916 \u0915\u093e \u0914\u0930 \u0905\u092a\u0928\u094b\u0902 \u0915\u093e \u0938\u093e\u0925 \u0916\u0941\u0936\u0940 \u0915\u093e \u0915\u093e\u0930\u0923 \u0915\u094d\u092f\u094b\u0902 \u0939\u0948?\u2019 \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u092c\u0924\u093e\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0939\u092e\u093e\u0930\u093e \u0936\u0930\u0940\u0930 \u092c\u0926\u0932\u0924\u0940 \u092c\u093e\u0939\u0930\u0940 \u092a\u0930\u093f\u0938\u094d\u0925\u093f\u0924\u093f\u092f\u094b\u0902 \u0915\u0947 \u0905\u0928\u0941\u0938\u093e\u0930 \u0924\u093e\u092a\u092e\u093e\u0928, \u0930\u0915\u094d\u0924\u091a\u093e\u092a \u0914\u0930 \u0936\u0930\u0940\u0930 \u0915\u0947 \u0924\u0930\u0932 \u092a\u0926\u093e\u0930\u094d\u0925\u094b\u0902 \u0915\u093e \u0906\u0902\u0924\u0930\u093f\u0915 \u0938\u0902\u0924\u0941\u0932\u0928 \u092c\u0928\u093e\u090f \u0930\u0916\u0924\u093e \u0939\u0948\u0964&nbsp; \u0907\u0938\u0947 \u0938\u092e\u0938\u094d\u0925\u093e\u092a\u0928 (\u0939\u094b\u092e\u093f\u092f\u094b\u0938\u094d\u091f\u0947\u0938\u093f\u0938) \u0915\u0939\u0924\u0947 \u0939\u0948\u0902\u0964 \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0915\u093e \u092e\u093e\u0928\u0928\u093e \u0939\u0948 \u0915\u093f \u0920\u0940\u0915 \u0909\u0938\u0940 \u092a\u094d\u0930\u0915\u093e\u0930 \u0939\u092e\u093e\u0930\u093e \u0926\u093f\u092e\u093e\u0917 \u092d\u0940 \u0938\u093e\u092e\u093e\u091c\u093f\u0915 \u091c\u0940\u0935\u0928 \u0914\u0930 \u0905\u0915\u0947\u0932\u0947\u092a\u0928 \u0915\u0947 \u092c\u0940\u091a \u0938\u0902\u0924\u0941\u0932\u0928 \u0915\u0940 \u0924\u0932\u093e\u0936 \u0915\u0930\u0924\u093e \u0939\u0948\u0964 \u0907\u0938\u0947 \u0909\u0928\u094d\u0939\u094b\u0902\u0928\u0947 \u0926\u093f\u092e\u093e\u0917 \u0915\u0940 \u092e\u093e\u0928\u0938\u093f\u0915 \u0938\u092e\u0938\u094d\u0925\u093f\u0924\u093f (mental homeostasis) \u0928\u093e\u092e \u0926\u093f\u092f\u093e \u0939\u0948\u0964 \u0939\u093e\u0932\u093e\u0902\u0915\u093f, \u0938\u093e\u092e\u093e\u091c\u093f\u0915 \u0938\u0902\u0924\u0941\u0932\u0928 \u0915\u0940 \u091c\u093c\u0930\u0942\u0930\u0924\u0947\u0902 \u0914\u0930 \u0938\u0940\u092e\u093e\u090f\u0902 \u0939\u0930 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0915\u0947 \u0932\u093f\u090f \u0905\u0932\u0917-\u0905\u0932\u0917 \u0939\u094b \u0938\u0915\u0924\u0940 \u0939\u0948\u0902\u0964 \u0915\u093f\u0938\u0940 \u0915\u094b \u0905\u0915\u0947\u0932\u0947 \u0930\u0939\u0928\u093e \u091c\u093c\u094d\u092f\u093e\u0926\u093e \u092a\u0938\u0902\u0926 \u0939\u094b\u0917\u093e, \u0924\u094b \u0915\u093f\u0938\u0940 \u0915\u094b \u092c\u0921\u093c\u0947 \u0938\u092e\u0942\u0939 \u092f\u093e \u0932\u094b\u0917\u094b\u0902 \u0915\u0947 \u0906\u0938\u092a\u093e\u0938, \u0932\u094b\u0917\u094b\u0902 \u0938\u0947 \u092e\u093f\u0932-\u091c\u0941\u0932\u0915\u0930 \u0930\u0939\u0928\u093e \u092a\u0938\u0902\u0926 \u0939\u094b\u0917\u093e\u0964&nbsp;<\/p>\n\n\n\n<p>\u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u0907\u0938\u0947 \u2018\u0905\u092a\u0928\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0915\u0940 \u0932\u093e\u0932\u0938\u093e\u2019 \u0915\u0939\u0924\u0947 \u0939\u0948\u0902\u0964 \u091c\u092c \u0915\u094b\u0908 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u092c\u0939\u0941\u0924 \u0932\u0902\u092c\u0947 \u0938\u092e\u092f \u0924\u0915 \u0905\u0915\u0947\u0932\u0947 \u0930\u0939\u0924\u093e \u0939\u0948 \u0924\u094b \u092e\u0938\u094d\u0924\u093f\u0937\u094d\u0915 \u0915\u0947 \u090f\u0915 \u0939\u093f\u0938\u094d\u0938\u0947 (\u0939\u093e\u092f\u092a\u094b\u0925\u0948\u0932\u0947\u092e\u0938) \u0915\u0940 \u0915\u0941\u091b \u0916\u093e\u0938 \u0915\u094b\u0936\u093f\u0915\u093e\u090f\u0902 \u0938\u0915\u094d\u0930\u093f\u092f \u0939\u094b \u091c\u093e\u0924\u0940 \u0939\u0948\u0902\u0964 \u0907\u0928 \u0915\u094b\u0936\u093f\u0915\u093e\u0913\u0902 \u0915\u0940 \u0938\u0915\u094d\u0930\u093f\u092f\u0924\u093e \u0915\u0947 \u0915\u093e\u0930\u0923 \u0905\u0915\u0947\u0932\u093e\u092a\u0928 \u091d\u0947\u0932 \u0930\u0939\u093e \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u092c\u0947\u091a\u0948\u0928\u0940, \u0909\u0926\u093e\u0938\u0940 \u0914\u0930 \u0926\u0941\u0916 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0924\u093e \u0939\u0948\u0964 \u0926\u0942\u0938\u0930\u0940 \u0913\u0930, \u091c\u092c \u0905\u092a\u0928\u094b\u0902 \u0938\u0947 \u092e\u093f\u0932\u0928\u0947 \u092a\u0930 \u0905\u0915\u0947\u0932\u093e\u092a\u0928 \u0926\u0942\u0930 \u0939\u094b\u0924\u093e \u0939\u0948 \u0924\u092c \u092e\u0938\u094d\u0924\u093f\u0937\u094d\u0915 \u0915\u0940 \u0905\u0928\u094d\u092f \u0915\u094b\u0936\u093f\u0915\u093e\u090f\u0902 \u0938\u0915\u094d\u0930\u093f\u092f \u0939\u094b\u0924\u0940 \u0939\u0948\u0902\u0964 \u0907\u0938\u0938\u0947 \u0921\u094b\u092a\u093e\u092e\u093e\u0907\u0928 (dopamine) \u0928\u093e\u092e \u0915\u093e \u0930\u0938\u093e\u092f\u0928 \u0938\u094d\u0930\u093e\u0935\u093f\u0924 \u0939\u094b\u0924\u093e \u0939\u0948; \u091c\u094b \u0935\u0948\u0938\u093e \u0939\u0940 \u0938\u0941\u0916\u0926 \u090f\u0939\u0938\u093e\u0938 \u0926\u0947\u0924\u093e \u0939\u0948 \u091c\u0948\u0938\u093e \u0915\u093f\u0938\u0940 \u092d\u0942\u0916\u0947 \u0915\u094b \u0916\u093e\u0928\u093e \u092e\u093f\u0932\u0928\u0947 \u092a\u0930 \u0939\u094b\u0924\u093e \u0939\u0948\u0964\u00a0<\/p>\n\n\n\n<p>\u0915\u0941\u0926\u0930\u0924 \u092e\u0947\u0902 \u0915\u0908 \u091c\u0940\u0935\u094b\u0902 \u0915\u094b \u0935\u093f\u092d\u093f\u0928\u094d\u0928 \u0915\u093e\u0930\u0923\u094b\u0902 \u0938\u0947 \u0938\u092e\u0942\u0939 \u092f\u093e \u0938\u093e\u0925 \u0915\u0940 \u091c\u093c\u0930\u0942\u0930\u0924 \u0939\u094b\u0924\u0940 \u0939\u0948\u0964 \u092b\u093f\u0930 \u091a\u093e\u0939\u0947 \u0935\u094b \u0915\u0921\u093c\u093e\u0915\u0947 \u0915\u0940 \u0920\u0902\u0921 \u0938\u0947 \u092c\u091a\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u090f\u0915 \u0926\u0942\u0938\u0930\u0947 \u0938\u0947 \u091a\u093f\u092a\u0915\u0915\u0930 \u092c\u0948\u0920\u0928\u0947 \u0935\u093e\u0932\u0947 \u092a\u0915\u094d\u0937\u0940 \u0939\u094b\u0902, \u0926\u0941\u0936\u094d\u092e\u0928\u094b\u0902 \u0938\u0947 \u0938\u0941\u0930\u0915\u094d\u0937\u093e \u0915\u0947 \u0932\u093f\u090f \u0930\u0947\u0917\u093f\u0938\u094d\u0924\u093e\u0928 \u092e\u0947\u0902 \u092c\u0921\u093c\u0947 \u0938\u092e\u0942\u0939\u094b\u0902 \u092e\u0947\u0902 \u0930\u0939\u0928\u0947 \u0935\u093e\u0932\u0947 \u092e\u0940\u0930\u0915\u0948\u091f \u0914\u0930 \u092d\u094b\u091c\u0928 \u0915\u0940 \u0924\u0932\u093e\u0936\/\u0936\u093f\u0915\u093e\u0930 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u091d\u0941\u0902\u0921 \u092e\u0947\u0902 \u0930\u0939\u0928\u0947 \u0935\u093e\u0932\u0940 \u0928\u0940\u0932\u0917\u093e\u092f, \u091c\u093c\u0947\u092c\u0930\u093e, \u092f\u093e \u0932\u0915\u094d\u0915\u0921\u093c\u092c\u0917\u094d\u0918\u0947\u0964 \u0926\u0942\u0938\u0930\u0940 \u0913\u0930, \u0915\u0941\u091b \u091c\u093e\u0928\u0935\u0930 \u0910\u0938\u0947 \u092d\u0940 \u0939\u0948\u0902 \u091c\u094b \u091c\u093c\u094d\u092f\u093e\u0926\u093e\u0924\u0930 \u0905\u0915\u0947\u0932\u0947 \u0930\u0939\u0924\u0947 \u0939\u0948\u0902, \u091c\u0948\u0938\u0947 \u0913\u0930\u093e\u0902\u0917\u0941\u091f\u093e\u0928 \u0905\u0915\u0947\u0932\u0947 \u0905\u092a\u0928\u093e \u0916\u093e\u0928\u093e \u0922\u0942\u0902\u0922\u0924\u0947 \u0939\u0948\u0902, \u0924\u0947\u0902\u0926\u0941\u090f \u0905\u0915\u0947\u0932\u0947 \u0939\u0940 \u0936\u093f\u0915\u093e\u0930 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902\u0964<\/p>\n\n\n\n<p>\u0926\u0930\u0905\u0938\u0932, \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u091a\u0942\u0939\u094b\u0902 \u092a\u0930 \u0936\u094b\u0927 \u0915\u0930\u0915\u0947 \u092f\u0939 \u091c\u093e\u0928\u0928\u093e \u091a\u093e\u0939 \u0930\u0939\u0947 \u0925\u0947 \u0915\u093f \u091a\u0942\u0939\u0947 \u0915\u092c \u0914\u0930 \u0915\u0948\u0938\u0947 \u0905\u0915\u0947\u0932\u093e\u092a\u0928 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0924\u0947 \u0939\u0948\u0902? \u0907\u0938\u0915\u0947 \u0932\u093f\u090f \u0909\u0928\u094d\u0939\u094b\u0902\u0928\u0947 \u092a\u093f\u0902\u091c\u0930\u0947 \u0915\u0947 \u092c\u0940\u091a \u092e\u0947\u0902 \u0910\u0938\u0940 \u091c\u093e\u0932\u0940 \u0932\u0917\u093e \u0926\u0940 \u091c\u093f\u0938\u0938\u0947 \u091a\u0942\u0939\u0947 \u090f\u0915-\u0926\u0942\u0938\u0930\u0947 \u0915\u094b \u0926\u0947\u0916 \u0938\u0915\u0924\u0947 \u0925\u0947, \u0938\u0941\u0928 \u0938\u0915\u0924\u0947 \u0925\u0947, \u0938\u0942\u0902\u0918 \u092d\u0940 \u0938\u0915\u0924\u0947 \u0925\u0947 &#8211; \u0915\u0947\u0935\u0932 \u091b\u0942 \u0928\u0939\u0940\u0902 \u0938\u0915\u0924\u0947 \u0925\u0947\u0964 \u092a\u0930\u093f\u0923\u093e\u092e \u092f\u0939 \u0939\u0941\u0906 \u0915\u093f \u0938\u093e\u0925\u0940 \u091a\u0942\u0939\u0947 \u0938\u093e\u092e\u0928\u0947 \u0939\u094b\u0924\u0947 \u0939\u0941\u090f \u092d\u0940 \u0935\u0947 \u0905\u0915\u0947\u0932\u093e \u0914\u0930 \u0909\u0926\u093e\u0938 (sad) \u092e\u0939\u0938\u0942\u0938 \u0915\u0930 \u0930\u0939\u0947 \u0925\u0947\u0964 \u0909\u0938\u0915\u0947 \u092c\u093e\u0926 \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0928\u0947 \u0905\u0915\u0947\u0932\u0947 \u0930\u0939 \u0930\u0939\u0947 \u091a\u0942\u0939\u094b\u0902 \u0915\u094b \u0926\u094b \u0916\u093e\u0938 \u0938\u0941\u0930\u0902\u0917 \u0935\u093e\u0932\u0947 \u0930\u093e\u0938\u094d\u0924\u094b\u0902 \u0915\u093e \u0935\u093f\u0915\u0932\u094d\u092a \u0926\u093f\u092f\u093e\u0964 \u090f\u0915 \u0930\u093e\u0938\u094d\u0924\u0947 \u092e\u0947\u0902 \u0928\u0930\u094d\u092e-\u092e\u0916\u092e\u0932\u0940 \u091a\u093e\u0926\u0930 \u0925\u0940 \u0914\u0930 \u0926\u0942\u0938\u0930\u093e \u0930\u093e\u0938\u094d\u0924\u093e \u0938\u0916\u094d\u0924 \u0925\u093e\u0964 \u0909\u0928\u094d\u0939\u094b\u0902\u0928\u0947 \u092a\u093e\u092f\u093e \u0915\u093f \u0905\u0915\u0947\u0932\u0947\u092a\u0928 \u0938\u0947 \u091c\u0941\u091d \u0930\u0939\u0947 \u091a\u0942\u0939\u094b\u0902 \u0928\u0947 \u0938\u0916\u094d\u0924 \u0930\u093e\u0938\u094d\u0924\u0947 \u0915\u0947 \u092c\u091c\u093e\u092f \u0928\u0930\u094d\u092e-\u092e\u0916\u092e\u0932\u0940 \u091a\u093e\u0926\u0930 \u0935\u093e\u0932\u0947 \u0930\u093e\u0938\u094d\u0924\u0947 \u0915\u094b \u091a\u0941\u0928\u093e\u0964 \u0907\u0938\u0938\u0947 \u092f\u0939 \u0938\u093e\u092c\u093f\u0924 \u0939\u0941\u0906 \u0915\u093f (\u091a\u0942\u0939\u094b\u0902 \u092e\u0947\u0902) \u0905\u0915\u0947\u0932\u093e\u092a\u0928(lonliness) \u0926\u0942\u0930 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u0947\u0935\u0932 \u0926\u0947\u0916\u0928\u093e, \u0938\u0941\u0928\u0928\u093e \u092f\u093e \u0938\u0942\u0902\u0918\u0928\u093e \u0915\u093e\u092b\u0940 \u0928\u0939\u0940\u0902 \u0939\u0948 \u092c\u0932\u094d\u0915\u093f \u0936\u093e\u0930\u0940\u0930\u093f\u0915 \u0938\u094d\u092a\u0930\u094d\u0936 \u0938\u092c\u0938\u0947 \u091c\u093c\u094d\u092f\u093e\u0926\u093e \u091c\u093c\u0930\u0942\u0930\u0940 \u0939\u0948\u0964 \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u092c\u0924\u093e\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u0914\u0930 \u091a\u0942\u0939\u094b\u0902 \u0915\u0940 \u0924\u094d\u0935\u091a\u093e \u092e\u0947\u0902 \u0916\u093e\u0938 \u0938\u0902\u0935\u0947\u0926\u0915 \u0914\u0930 \u0907\u0902\u0926\u094d\u0930\u093f\u092f\u093e\u0902 (Sensors and senses) \u0939\u094b\u0924\u0940 \u0939\u0948\u0902 \u091c\u094b \u0938\u094d\u0928\u0947\u0939 \u092d\u0930\u0947 \u0938\u094d\u092a\u0930\u094d\u0936 \u0938\u0947 \u092e\u0938\u094d\u0924\u093f\u0937\u094d\u0915 \u0915\u094b \u0924\u0941\u0930\u0902\u0924 \u0938\u0915\u094d\u0930\u093f\u092f \u0915\u0930\u0915\u0947 \u0938\u0941\u0930\u0915\u094d\u0937\u093f\u0924 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0935\u093e\u0924\u0940 \u0939\u0948\u0902, \u0907\u0938\u0947 \u2018\u0938\u094d\u092a\u0930\u094d\u0936 \u0915\u0940 \u0924\u093e\u0915\u0924\u2019 \u0915\u0939\u093e \u0917\u092f\u093e\u0964<\/p>\n\n\n\n<p>\u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0928\u0947 \u0928\u0930 \u0914\u0930 \u092e\u093e\u0926\u093e \u091a\u0942\u0939\u094b\u0902 \u092e\u0947\u0902 \u092d\u0940 \u0905\u0915\u0947\u0932\u0947\u092a\u0928 \u0915\u0947 \u0905\u0938\u0930 \u0915\u094b \u0926\u0947\u0916\u093e\u0964 \u0909\u0928\u094d\u0939\u094b\u0902\u0928\u0947 \u092a\u093e\u092f\u093e \u0915\u093f \u092e\u093e\u0926\u093e \u091a\u0942\u0939\u0947 \u0932\u0902\u092c\u093e \u0935\u0915\u094d\u0924 \u0905\u0915\u0947\u0932\u0947 \u092c\u093f\u0924\u093e\u0928\u0947 \u0915\u0947 \u092c\u093e\u0926 \u091c\u093c\u094d\u092f\u093e\u0926\u093e \u092e\u093f\u0932\u0928\u0938\u093e\u0930 \u0939\u094b \u0917\u0908\u0902\u0964 \u0935\u0939\u0940\u0902 \u0928\u0930 \u091a\u0942\u0939\u0947 \u0905\u0915\u0947\u0932\u0947 \u0930\u0939\u0928\u0947 \u0938\u0947 \u091a\u093f\u0921\u093c\u091a\u093f\u0921\u093c\u0947, \u0917\u0941\u0938\u094d\u0938\u0948\u0932, \u0914\u0930 \u0905\u092a\u0928\u0947 \u0907\u0932\u093e\u0915\u0947 \u0915\u0947 \u092a\u094d\u0930\u0924\u093f \u0938\u0902\u0935\u0947\u0926\u0928\u0936\u0940\u0932 \u0939\u094b \u0917\u090f\u0964&nbsp;<\/p>\n\n\n\n<p>\u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u0914\u0930 \u091a\u0942\u0939\u094b\u0902 \u0915\u0947 \u0917\u0939\u0928 \u092e\u0938\u094d\u0924\u093f\u0937\u094d\u0915 \u0915\u094d\u0937\u0947\u0924\u094d\u0930 \u092c\u0939\u0941\u0924 \u0939\u0926 \u0924\u0915 \u0938\u092e\u093e\u0928 \u0939\u0948\u0902\u0964 \u0907\u0938\u0932\u093f\u090f \u091a\u0942\u0939\u094b\u0902 \u0915\u0947 \u0905\u0915\u0947\u0932\u0947\u092a\u0928 \u0935\u093e\u0932\u0947 \u0935\u094d\u092f\u0935\u0939\u093e\u0930 \u0915\u094b \u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u0915\u0947 \u0905\u0915\u0947\u0932\u0947\u092a\u0928 \u0938\u0947 \u0939\u094b\u0928\u0947 \u0935\u093e\u0932\u0947 \u0935\u094d\u092f\u0935\u0939\u093e\u0930\u094b\u0902 \u0914\u0930 \u0938\u092e\u0938\u094d\u092f\u093e\u0913\u0902 \u0915\u094b \u0938\u092e\u091d\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0905\u0927\u094d\u092f\u092f\u0928 \u0915\u093f\u092f\u093e \u091c\u093e \u0930\u0939\u093e \u0939\u0948\u0964<\/p>\n\n\n\n<p>\u0936\u094b\u0927 \u092c\u0924\u093e\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u091c\u0947\u0932 \u0915\u0940 \u0905\u0915\u0947\u0932\u0940 \u0915\u094b\u0920\u0930\u0940 \u092e\u0947\u0902 \u0938\u091c\u093c\u093e \u0915\u093e\u091f \u0930\u0939\u0947 \u0915\u0948\u0926\u093f\u092f\u094b\u0902 \u0915\u094b \u092c\u0939\u0941\u0924 \u0932\u0902\u092c\u0947 \u0938\u092e\u092f \u0924\u0915 \u0905\u0915\u0947\u0932\u0947 \u0930\u0939\u0928\u0947 \u0915\u0947 \u0915\u093e\u0930\u0923 \u092c\u093e\u0939\u0930\u0940 \u0926\u0941\u0928\u093f\u092f\u093e \u0938\u0947 \u0921\u0930 \u0932\u0917\u0928\u0947 \u0932\u0917\u0924\u093e \u0939\u0948, \u0909\u0928\u0915\u093e \u092e\u0938\u094d\u0924\u093f\u0937\u094d\u0915 \u0932\u0917\u093e\u0924\u093e\u0930 \u0916\u0924\u0930\u093e (danger) \u0914\u0930 \u092c\u0947\u091a\u0948\u0928\u0940 \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0924\u093e \u0939\u0948\u0964 \u092e\u093e\u0928\u0938\u093f\u0915 \u0938\u0902\u0924\u0941\u0932\u0928 \u092c\u093f\u0917\u0921\u093c\u0928\u0947 \u0915\u0947 \u0938\u093e\u0925-\u0938\u093e\u0925 \u0935\u0947 \u0932\u094b\u0917\u094b\u0902 \u0938\u0947 \u092e\u093f\u0932\u0928\u0947 \u0914\u0930 \u0938\u093e\u092e\u0928\u0947 \u0906\u0928\u0947 \u0938\u0947 \u0915\u0924\u0930\u093e\u0928\u0947 \u0932\u0917\u0924\u0947 \u0939\u0948\u0902\u0964<\/p>\n\n\n\n<p>\u0905\u0915\u0947\u0932\u0947\u092a\u0928 \u0938\u0947 \u0938\u0947\u0939\u0924 \u092a\u0930 \u092c\u0941\u0930\u093e \u0905\u0938\u0930 \u0939\u094b\u0928\u0947 \u0915\u0947 \u0915\u093e\u0930\u0923 \u091c\u093c\u093f\u0902\u0926\u0917\u0940 \u0915\u0947 \u0938\u093e\u0932 \u092d\u0940 \u0915\u092e \u0939\u094b\u0928\u0947 \u0932\u0917\u0924\u0947 \u0939\u0948\u0902\u0964 \u0905\u0915\u0947\u0932\u0947\u092a\u0928 \u0938\u0947 \u0928 \u0938\u093f\u0930\u094d\u092b \u092e\u0928 \u0926\u0941\u0916\u0940 \u0930\u0939\u0924\u093e \u0939\u0948 \u092c\u0932\u094d\u0915\u093f \u0932\u0902\u092c\u0947 \u0938\u092e\u092f \u0938\u0947 \u0905\u0915\u0947\u0932\u093e \u092e\u0939\u0938\u0942\u0938 \u0915\u0930\u0928\u0947 \u0935\u093e\u0932\u0947 \u0932\u094b\u0917\u094b\u0902 \u0915\u094b \u0926\u093f\u0932 \u0915\u0940 \u092c\u0940\u092e\u093e\u0930\u0940, \u0938\u094d\u091f\u094d\u0930\u094b\u0915, \u0914\u0930 \u0915\u0948\u0902\u0938\u0930 \u091c\u0948\u0938\u0940 \u092c\u0940\u092e\u093e\u0930\u093f\u092f\u094b\u0902 \u0915\u093e \u0938\u093e\u092e\u0928\u093e \u0915\u0930\u0928\u093e \u092a\u0921\u093c \u0938\u0915\u0924\u093e \u0939\u0948\u0964 \u092f\u093e\u0928\u0940 \u0938\u092e\u092f \u0915\u0947 \u0938\u093e\u0925 \u092f\u0947 \u092e\u093e\u0928\u0938\u093f\u0915 \u0914\u0930 \u0936\u093e\u0930\u0940\u0930\u093f\u0915 \u092a\u0940\u0921\u093c\u093e (physical trauma) \u092e\u0947\u0902 \u092c\u0926\u0932 \u091c\u093e\u0924\u093e \u0939\u0948\u0964<\/p>\n\n\n\n<p>\u0935\u093f\u0936\u0947\u0937\u091c\u094d\u091e\u094b\u0902 \u0915\u0940 \u0938\u0932\u093e\u0939 \u0939\u0948 \u0915\u093f \u0938\u0902\u0924\u0941\u0932\u0928 \u092c\u0928\u093e\u090f \u0930\u0916\u0928\u093e \u0939\u0940 \u0905\u0915\u0947\u0932\u0947\u092a\u0928 \u0915\u0940 \u0938\u092e\u0938\u094d\u092f\u093e \u0915\u093e \u0938\u092e\u093e\u0927\u093e\u0928 \u0939\u0948\u0964 \u0916\u0941\u0926 \u0915\u0940 \u0938\u093e\u092e\u093e\u091c\u093f\u0915 \u0938\u0940\u092e\u093e\u0913\u0902 \u0915\u094b \u092a\u0939\u091a\u093e\u0928\u0915\u0930 \u0925\u094b\u0921\u093c\u093e \u0938\u092e\u092f \u0916\u0941\u0926 \u0915\u0947 \u0938\u093e\u0925 \u092c\u093f\u0924\u093e\u090f\u0902, \u0925\u094b\u0921\u093c\u093e \u0915\u0930\u0940\u092c\u0940 \u0932\u094b\u0917\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0914\u0930 \u0915\u092d\u0940-\u0915\u092d\u0940 \u0925\u094b\u0921\u093c\u093e \u0938\u092e\u092f \u092c\u0921\u093c\u0947 \u0938\u093e\u092e\u093e\u091c\u093f\u0915 \u0915\u093e\u0930\u094d\u092f\u0915\u094d\u0930\u092e\u094b\u0902 \u092e\u0947\u0902 \u0926\u0947\u0902\u0964 \u0907\u0938\u0938\u0947 \u0939\u0930 \u092a\u0930\u093f\u0938\u094d\u0925\u093f\u0924\u093f \u092e\u0947\u0902 \u092e\u0938\u094d\u0924\u093f\u0937\u094d\u0915 \u0916\u0941\u0936 \u0930\u0939\u0928\u093e \u0938\u0940\u0916\u0924\u093e \u0939\u0948\u0964 \u0906\u0916\u093f\u0930 \u092e\u0947\u0902, \u0935\u0948\u0938\u0947 \u0924\u094b \u0906\u091c\u0915\u0932 \u0932\u094b\u0917\u094b\u0902 \u0938\u0947 \u091c\u0941\u0921\u093c\u0947 \u0930\u0939\u0928\u093e \u0924\u0915\u0928\u0940\u0915\u0940 \u0938\u093e\u0927\u0928\u094b\u0902 \u0938\u0947 \u092c\u0939\u0941\u0924 \u0906\u0938\u093e\u0928 \u0939\u094b \u0917\u092f\u093e \u0939\u0948\u0964 \u0932\u0947\u0915\u093f\u0928 \u091c\u092c \u092d\u0940 \u092e\u094c\u0915\u093e \u0939\u094b, \u0938\u094d\u0928\u0947\u0939-\u0938\u094d\u092a\u0930\u094d\u0936 \u0915\u0947 \u091c\u093c\u0930\u093f\u090f \u0905\u092a\u0928\u093e\u092a\u0928 \u091c\u0924\u093e\u0928\u093e \u0939\u092e\u093e\u0930\u0947 \u0924\u0928, \u092e\u0928 \u0914\u0930 \u092e\u0938\u094d\u0924\u093f\u0937\u094d\u0915 \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u0938\u0940 \u091c\u0921\u093c\u0940-\u092c\u0942\u091f\u0940 \u0938\u0947 \u0915\u092e \u0928\u0939\u0940\u0902 \u0939\u0948\u0902\u0964 <strong><em>&nbsp;(\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938)<\/em><\/strong><\/p>\n\n\n\n<p>\u0928\u094b\u091f: \u0938\u094d\u0930\u094b\u0924 \u092e\u0947\u0902 \u091b\u092a\u0947 \u0932\u0947\u0916\u094b\u0902 \u0915\u0947 \u0935\u093f\u091a\u093e\u0930 \u0932\u0947\u0916\u0915\u094b\u0902 \u0915\u0947 \u0939\u0948\u0902\u0964 \u090f\u0915\u0932\u0935\u094d\u092f \u0915\u093e \u0907\u0928\u0938\u0947 \u0938\u0939\u092e\u0924 \u0939\u094b\u0928\u093e \u0906\u0935\u0936\u094d\u092f\u0915 \u0928\u0939\u0940\u0902 \u0939\u0948\u0964<br>Photo Credit: <a href=\"https:\/\/i.guim.co.uk\/img\/media\/cfa9d5667ecc480edae5622a8e36d51c665150aa\/0_121_7123_4275\/master\/7123.jpg?width=620&amp;dpr=2&amp;s=none&amp;crop=none\" type=\"link\" id=\"https:\/\/i.guim.co.uk\/img\/media\/cfa9d5667ecc480edae5622a8e36d51c665150aa\/0_121_7123_4275\/master\/7123.jpg?width=620&amp;dpr=2&amp;s=none&amp;crop=none\">https:\/\/i.guim.co.uk\/img\/media\/cfa9d5667ecc480edae5622a8e36d51c665150aa\/0_121_7123_4275\/master\/7123.jpg?width=620&amp;dpr=2&amp;s=none&amp;crop=none<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u0915\u094b \u0938\u093e\u0925\u093f\u092f\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0930\u0939\u0928\u093e \u092a\u0938\u0902\u0926 \u0939\u0948\u0964 \u0915\u094d\u092f\u093e \u0907\u0938\u0915\u0947 \u092a\u0940\u091b\u0947 \u0915\u094b\u0908 \u091c\u0940\u0935 \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u0915\u093e\u0930\u0923 \u0939\u0948?&nbsp;&nbsp; \u0907\u0938\u0947 \u0938\u092e\u091d\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0928\u0947 \u091c\u093e\u0928\u0935\u0930\u094b\u0902 \u0914\u0930 \u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u092a\u0930 \u0915\u0941\u091b \u0926\u093f\u0932\u091a\u0938\u094d\u092a \u0905\u0927\u094d\u092f\u092f\u0928 \u0915\u093f\u090f \u0939\u0948\u0902\u0964 \u0905\u0927\u094d\u092f\u092f\u0928 \u092c\u0924\u093e\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0938\u092e\u0942\u0939 \u092e\u0947\u0902 \u0930\u0939\u0928\u093e, \u092e\u093f\u0932\u0928\u093e-\u091c\u0941\u0932\u0928\u093e \u0915\u0947\u0935\u0932 \u092a\u0938\u0902\u0926 -\u0928\u093e\u092a\u0938\u0902\u0926 \u092e\u093e\u092e\u0932\u093e \u0928\u0939\u0940\u0902 \u0939\u0948 \u092c\u0932\u094d\u0915\u093f \u0930\u094b\u091f\u0940-\u0915\u092a\u0921\u093c\u093e-\u092e\u0915\u093e\u0928 \u0915\u0940 \u0924\u0930\u0939 \u092f\u0939 \u092d\u0940 \u0939\u092e\u093e\u0930\u0947 \u091c\u0940\u0935\u0928 \u0915\u093e \u0906\u0927\u093e\u0930 &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/\" class=\"more-link\">\u092a\u0922\u093c\u0928\u093e \u091c\u093e\u0930\u0940 \u0930\u0916\u0947\u0902<span class=\"screen-reader-text\"> &#8220;\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,11],"tags":[],"class_list":["post-7409","post","type-post","status-publish","format-standard","hentry","category-10","category-11"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902? - \u0938\u094d\u0930\u094b\u0924<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/\u0939\u092e-\u0938\u093e\u0925-\u0938\u093e\u0925-\u0939\u0948\u0902-\u0915\u0940-\u0924\u0921\u093c\u092a-\u0915\u094d\/\" \/>\n<meta property=\"og:locale\" content=\"hi_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902? - \u0938\u094d\u0930\u094b\u0924\" \/>\n<meta property=\"og:description\" content=\"\u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u0915\u094b \u0938\u093e\u0925\u093f\u092f\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0930\u0939\u0928\u093e \u092a\u0938\u0902\u0926 \u0939\u0948\u0964 \u0915\u094d\u092f\u093e \u0907\u0938\u0915\u0947 \u092a\u0940\u091b\u0947 \u0915\u094b\u0908 \u091c\u0940\u0935 \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u0915\u093e\u0930\u0923 \u0939\u0948?&nbsp;&nbsp; \u0907\u0938\u0947 \u0938\u092e\u091d\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0928\u0947 \u091c\u093e\u0928\u0935\u0930\u094b\u0902 \u0914\u0930 \u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u092a\u0930 \u0915\u0941\u091b \u0926\u093f\u0932\u091a\u0938\u094d\u092a \u0905\u0927\u094d\u092f\u092f\u0928 \u0915\u093f\u090f \u0939\u0948\u0902\u0964 \u0905\u0927\u094d\u092f\u092f\u0928 \u092c\u0924\u093e\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0938\u092e\u0942\u0939 \u092e\u0947\u0902 \u0930\u0939\u0928\u093e, \u092e\u093f\u0932\u0928\u093e-\u091c\u0941\u0932\u0928\u093e \u0915\u0947\u0935\u0932 \u092a\u0938\u0902\u0926 -\u0928\u093e\u092a\u0938\u0902\u0926 \u092e\u093e\u092e\u0932\u093e \u0928\u0939\u0940\u0902 \u0939\u0948 \u092c\u0932\u094d\u0915\u093f \u0930\u094b\u091f\u0940-\u0915\u092a\u0921\u093c\u093e-\u092e\u0915\u093e\u0928 \u0915\u0940 \u0924\u0930\u0939 \u092f\u0939 \u092d\u0940 \u0939\u092e\u093e\u0930\u0947 \u091c\u0940\u0935\u0928 \u0915\u093e \u0906\u0927\u093e\u0930 &hellip; \u092a\u0922\u093c\u0928\u093e \u091c\u093e\u0930\u0940 \u0930\u0916\u0947\u0902 &quot;\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902?&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/\u0939\u092e-\u0938\u093e\u0925-\u0938\u093e\u0925-\u0939\u0948\u0902-\u0915\u0940-\u0924\u0921\u093c\u092a-\u0915\u094d\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0938\u094d\u0930\u094b\u0924\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T07:01:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-29T10:19:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"928\" \/>\n\t<meta property=\"og:image:height\" content=\"555\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/\"},\"author\":{\"name\":\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab\"},\"headline\":\"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902?\",\"datePublished\":\"2026-07-15T07:01:01+00:00\",\"dateModified\":\"2026-07-29T10:19:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/\"},\"wordCount\":62,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg\",\"articleSection\":[\"\u0905\u0928\u0941\u0938\u0902\u0927\u093e\u0928\",\"\u091a\u093f\u0915\u093f\u0924\u094d\u0938\u093e \/ \u0938\u094d\u0935\u093e\u0938\u094d\u0925\u094d\u092f\"],\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/\",\"url\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/\",\"name\":\"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902? - \u0938\u094d\u0930\u094b\u0924\",\"isPartOf\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg\",\"datePublished\":\"2026-07-15T07:01:01+00:00\",\"dateModified\":\"2026-07-29T10:19:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#breadcrumb\"},\"inLanguage\":\"hi-IN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#primaryimage\",\"url\":\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg\",\"contentUrl\":\"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg\",\"width\":928,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.srotefeatures.in\/srote\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#website\",\"url\":\"https:\/\/www.srotefeatures.in\/srote\/\",\"name\":\"\u0938\u094d\u0930\u094b\u0924\",\"description\":\"\u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u090f\u0935\u0902 \u091f\u0947\u0915\u094d\u0928\u0949\u0932\u0949\u091c\u0940 \u092b\u0940\u091a\u0930\u094d\u0938\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.srotefeatures.in\/srote\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hi-IN\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab\",\"name\":\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g\",\"caption\":\"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938\"},\"url\":\"https:\/\/www.srotefeatures.in\/srote\/author\/srote\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902? - \u0938\u094d\u0930\u094b\u0924","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/\u0939\u092e-\u0938\u093e\u0925-\u0938\u093e\u0925-\u0939\u0948\u0902-\u0915\u0940-\u0924\u0921\u093c\u092a-\u0915\u094d\/","og_locale":"hi_IN","og_type":"article","og_title":"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902? - \u0938\u094d\u0930\u094b\u0924","og_description":"\u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u0915\u094b \u0938\u093e\u0925\u093f\u092f\u094b\u0902 \u0915\u0947 \u0938\u093e\u0925 \u0930\u0939\u0928\u093e \u092a\u0938\u0902\u0926 \u0939\u0948\u0964 \u0915\u094d\u092f\u093e \u0907\u0938\u0915\u0947 \u092a\u0940\u091b\u0947 \u0915\u094b\u0908 \u091c\u0940\u0935 \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915 \u0915\u093e\u0930\u0923 \u0939\u0948?&nbsp;&nbsp; \u0907\u0938\u0947 \u0938\u092e\u091d\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0935\u0948\u091c\u094d\u091e\u093e\u0928\u093f\u0915\u094b\u0902 \u0928\u0947 \u091c\u093e\u0928\u0935\u0930\u094b\u0902 \u0914\u0930 \u092e\u0928\u0941\u0937\u094d\u092f\u094b\u0902 \u092a\u0930 \u0915\u0941\u091b \u0926\u093f\u0932\u091a\u0938\u094d\u092a \u0905\u0927\u094d\u092f\u092f\u0928 \u0915\u093f\u090f \u0939\u0948\u0902\u0964 \u0905\u0927\u094d\u092f\u092f\u0928 \u092c\u0924\u093e\u0924\u0947 \u0939\u0948\u0902 \u0915\u093f \u0938\u092e\u0942\u0939 \u092e\u0947\u0902 \u0930\u0939\u0928\u093e, \u092e\u093f\u0932\u0928\u093e-\u091c\u0941\u0932\u0928\u093e \u0915\u0947\u0935\u0932 \u092a\u0938\u0902\u0926 -\u0928\u093e\u092a\u0938\u0902\u0926 \u092e\u093e\u092e\u0932\u093e \u0928\u0939\u0940\u0902 \u0939\u0948 \u092c\u0932\u094d\u0915\u093f \u0930\u094b\u091f\u0940-\u0915\u092a\u0921\u093c\u093e-\u092e\u0915\u093e\u0928 \u0915\u0940 \u0924\u0930\u0939 \u092f\u0939 \u092d\u0940 \u0939\u092e\u093e\u0930\u0947 \u091c\u0940\u0935\u0928 \u0915\u093e \u0906\u0927\u093e\u0930 &hellip; \u092a\u0922\u093c\u0928\u093e \u091c\u093e\u0930\u0940 \u0930\u0916\u0947\u0902 \"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902?\"","og_url":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/\u0939\u092e-\u0938\u093e\u0925-\u0938\u093e\u0925-\u0939\u0948\u0902-\u0915\u0940-\u0924\u0921\u093c\u092a-\u0915\u094d\/","og_site_name":"\u0938\u094d\u0930\u094b\u0924","article_published_time":"2026-07-15T07:01:01+00:00","article_modified_time":"2026-07-29T10:19:36+00:00","og_image":[{"width":928,"height":555,"url":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg","type":"image\/jpeg"}],"author":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938","twitter_card":"summary_large_image","twitter_misc":{"\u0926\u094d\u0935\u093e\u0930\u093e \u0932\u093f\u0916\u093f\u0924":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#article","isPartOf":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/"},"author":{"name":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938","@id":"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab"},"headline":"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902?","datePublished":"2026-07-15T07:01:01+00:00","dateModified":"2026-07-29T10:19:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/"},"wordCount":62,"commentCount":0,"image":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#primaryimage"},"thumbnailUrl":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg","articleSection":["\u0905\u0928\u0941\u0938\u0902\u0927\u093e\u0928","\u091a\u093f\u0915\u093f\u0924\u094d\u0938\u093e \/ \u0938\u094d\u0935\u093e\u0938\u094d\u0925\u094d\u092f"],"inLanguage":"hi-IN","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/","url":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/","name":"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902? - \u0938\u094d\u0930\u094b\u0924","isPartOf":{"@id":"https:\/\/www.srotefeatures.in\/srote\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#primaryimage"},"image":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#primaryimage"},"thumbnailUrl":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg","datePublished":"2026-07-15T07:01:01+00:00","dateModified":"2026-07-29T10:19:36+00:00","author":{"@id":"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab"},"breadcrumb":{"@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#breadcrumb"},"inLanguage":"hi-IN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/"]}]},{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#primaryimage","url":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg","contentUrl":"https:\/\/www.srotefeatures.in\/srote\/wp-content\/uploads\/2026\/07\/saath-saath-.jpg","width":928,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/www.srotefeatures.in\/srote\/2026\/07\/%e0%a4%b9%e0%a4%ae-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b8%e0%a4%be%e0%a4%a5-%e0%a4%b9%e0%a5%88%e0%a4%82-%e0%a4%95%e0%a5%80-%e0%a4%a4%e0%a4%a1%e0%a4%bc%e0%a4%aa-%e0%a4%95%e0%a5%8d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.srotefeatures.in\/srote\/"},{"@type":"ListItem","position":2,"name":"\u2018\u0939\u092e \u0938\u093e\u0925-\u0938\u093e\u0925 \u0939\u0948\u0902\u2019 \u0915\u0940 \u0924\u0921\u093c\u092a \u0915\u094d\u092f\u094b\u0902?"}]},{"@type":"WebSite","@id":"https:\/\/www.srotefeatures.in\/srote\/#website","url":"https:\/\/www.srotefeatures.in\/srote\/","name":"\u0938\u094d\u0930\u094b\u0924","description":"\u0935\u093f\u091c\u094d\u091e\u093e\u0928 \u090f\u0935\u0902 \u091f\u0947\u0915\u094d\u0928\u0949\u0932\u0949\u091c\u0940 \u092b\u0940\u091a\u0930\u094d\u0938","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.srotefeatures.in\/srote\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hi-IN"},{"@type":"Person","@id":"https:\/\/www.srotefeatures.in\/srote\/#\/schema\/person\/25de3014b0ad954e6489614b2246aeab","name":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938","image":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/91d0ee323ccbcff14465ae42297cc4877b6fe7fe3beca4cd7343428817691db2?s=96&d=mm&r=g","caption":"\u0938\u094d\u0930\u094b\u0924 \u092b\u0940\u091a\u0930\u094d\u0938"},"url":"https:\/\/www.srotefeatures.in\/srote\/author\/srote\/"}]}},"_links":{"self":[{"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/posts\/7409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/comments?post=7409"}],"version-history":[{"count":3,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/posts\/7409\/revisions"}],"predecessor-version":[{"id":7506,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/posts\/7409\/revisions\/7506"}],"wp:attachment":[{"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/media?parent=7409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/categories?post=7409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.srotefeatures.in\/srote\/wp-json\/wp\/v2\/tags?post=7409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}